{"id":5700,"date":"2019-03-12T00:00:00","date_gmt":"2019-03-11T23:00:00","guid":{"rendered":"https:\/\/sanmames.athletic-club.eus\/2019\/03\/12\/la-campa-de-los-ingleses-le-terrain-des-anglais-a-bilbao\/"},"modified":"2023-01-24T11:52:48","modified_gmt":"2023-01-24T10:52:48","slug":"terrain-des-anglais-bilbao","status":"publish","type":"post","link":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/","title":{"rendered":"La Campa de los Ingleses (Le Terrain des Anglais) \u00e0 Bilbao"},"content":{"rendered":"\n\r\n<p class='entradilla'>La <em>Campa de los Ingleses<\/em> \u00e0 Bilbao est un lieu historique, germe de la passion pour le football dans la capitale biscayenne et origine du c\u00e9l\u00e8bre Athletic Club.<\/p>\r\n\r\nC\u2019est pourquoi, cet ancien lieu qui c\u00e8de aujourd\u2019hui son nom \u00e0 plus d\u2019un recoin de la ville m\u00e9rite quelques mots pour relater son histoire.\r\n<h2 class='h2 swing'>La Campa de los Ingleses \u00e0 Bilbao, qu\u2019est-ce que c\u2019est et o\u00f9 est-ce ?<\/h2>\r\nQuand on parle de <em>La Campa de los Ingleses<\/em> \u00e0 Bilbao on peut se r\u00e9f\u00e9rer \u00e0 <strong>trois endroits diff\u00e9rents :<\/strong> l\u2019ancien quai, le parc actuel ou la taverne du stade de San Mam\u00e9s. Nous allons voir \u00e0 quoi correspond chacun d\u2019eux.\r\n<h3 class='h3 swing'>Le quai La Campa de los Ingleses<\/h3>\r\nCet espace longeait depuis le XVIIe si\u00e8cle et jusqu\u2019\u00e0 1908 la rive gauche de la Ria de Bilbao, faisant partie de ce que l\u2019on conna\u00eet aujourd\u2019hui comme <strong>Abandoibarra<\/strong>.\r\n\r\nCette aire, qui fut un cimeti\u00e8re britannique en ce temps, eut divers usages, comme servir de piste d\u2019atterrissage ou de terrain de football, entre autres.\r\n\r\nN\u00e9anmoins, c\u2019est au sport qu\u2019on doit que sa d\u00e9nomination (le nom qu\u2019il recevait) soit arriv\u00e9e jusqu\u2019\u00e0 nos jours et qu\u2019elle rev\u00eate de ce fait une valeur historique incalculable.\r\n\r\n<strong>C\u2019est sur ce terrain ou \u00ab campa \u00bb que les marins anglais qui d\u00e9barquaient \u00e0 Bilbao des bateaux Mac Andrews jouaient au football<\/strong>, une pratique jusqu\u2019alors inconnue pour les habitants de Bilbao.\r\n\r\nOn peut trouver aujourd\u2019hui dans ce lieu une plaque comm\u00e9morative pour rappeler que c\u2019est pr\u00e9cis\u00e9ment l\u00e0 qu\u2019a germ\u00e9 la passion pour le football et l\u2019Athletic Club \u00e0 <a href=\"http:\/\/visitsanmames.com\/que-ver-bilbao\/\">Bilbao<\/a>.\r\n<h3 class='h3 swing'>Le parc La Campa de los Ingleses<\/h3>\r\nAujourd\u2019hui, cet espace est assez diff\u00e9rent de ce qu\u2019il \u00e9tait alors. Environ 25 000 m\u00e8tres carr\u00e9s forment aujourd\u2019hui <strong>le Parc de <em>La Campa de los Ingleses<\/em><\/strong>, \u0153uvre de la <strong>paysagiste Diana Balmori<\/strong>.\r\n\r\nUn espace vert qui s\u2019\u00e9tend entre le <a href=\"http:\/\/www.guggenheim-bilbao.eus\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Mus\u00e9e Guggenheim de Bilbao<\/strong><\/a> et le Pont de Deusto, qui accueille \u00e0 son tour d\u2019autres lieux embl\u00e9matiques typiques de notre temps, comme la Tour Iberdrola ou la <a href=\"http:\/\/biblioteca.deusto.es\/cs\/Satellite\/biblioteca\/es\/biblioteca-crai\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Biblioth\u00e8que de l\u2019Universit\u00e9 de Deusto<\/strong><\/a>.\r\n<h3 class='h3 swing'>La taverne La Campa de los Ingleses<\/h3>\r\nEn dernier lieu se trouve la taverne <a href=\"https:\/\/sanmames.athletic-club.eus\/area-gastro-san-mames\/\"><em>La Campa de los Ingleses<\/em><\/a>, taverne gastronomique de San Mam\u00e9s situ\u00e9e au premier \u00e9tage du stade.\r\n\r\nComme on peut l\u2019imaginer, son nom d\u00e9coule du lieu dont nous parlons, le premier o\u00f9 s\u2019est disput\u00e9 un match de football en Biscaye, le quai de <em>La Campa de los Ingleses<\/em>.\r\n\r\nAujourd\u2019hui, cet endroit au c\u0153ur m\u00eame du football pour les habitants de Bilbao, <strong>allie histoire et tradition dans un nouveau concept de taverne<\/strong>. Le lieu id\u00e9al o\u00f9 c\u00e9l\u00e9brer les victoires de l\u2019Athletic et ouvert tous les jours de la semaine, sauf les jours de match.\r\n\r\nEn d\u00e9finitive, une taverne dot\u00e9e d\u2019une \u00e2me exceptionnelle, \u00e0 ne pas manquer si vous avez entendu des histoires et des l\u00e9gendes comme celles sur <em>La Campa de los Ingleses<\/em>.\r\n\r\n\u00a0\r\n\r\n<p class='swing'><!--HubSpot Call-to-Action Code --><span class=\"hs-cta-wrapper\" id=\"hs-cta-wrapper-23af3c36-7fbe-478e-8fdf-67a9131ba6c6\"><span class=\"hs-cta-node hs-cta-23af3c36-7fbe-478e-8fdf-67a9131ba6c6\" id=\"hs-cta-23af3c36-7fbe-478e-8fdf-67a9131ba6c6\"><!--[if lte IE 8]><div id=\"hs-cta-ie-element\"><\/div><![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/4626477\/23af3c36-7fbe-478e-8fdf-67a9131ba6c6\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"hs-cta-img\" id=\"hs-cta-img-23af3c36-7fbe-478e-8fdf-67a9131ba6c6\" style=\"border-width:0px;\" height=\"465\" width=\"1368\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4626477\/23af3c36-7fbe-478e-8fdf-67a9131ba6c6.png\" alt=\"Nueva llamada a la acci\u00f3n\"\/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(4626477, '23af3c36-7fbe-478e-8fdf-67a9131ba6c6', {\"useNewLoader\":\"true\",\"region\":\"na1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\r\n\r\n\u00a0\r\n\n","protected":false},"excerpt":{"rendered":"<p>C\u2019est pourquoi, cet ancien lieu qui c\u00e8de aujourd\u2019hui son nom \u00e0 plus d\u2019un recoin de la ville m\u00e9rite quelques mots pour relater son histoire. La Campa de los Ingleses \u00e0 Bilbao, qu\u2019est-ce que c\u2019est et o\u00f9 est-ce ? Quand on parle de La Campa de los Ingleses \u00e0 Bilbao on peut se r\u00e9f\u00e9rer \u00e0 trois [&hellip;]<\/p>\n","protected":false},"author":293,"featured_media":5276,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[73],"tags":[254,255],"class_list":["post-5700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-visiter-bilbao","tag-mejores-sitios-bilbao-fr","tag-paseo-por-bilbao-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Campa de los Ingleses (Le Terrain des Anglais) \u00e0 Bilbao | Visit San Mames<\/title>\n<meta name=\"description\" content=\"La Campa de los Ingleses \u00e0 Bilbao est un lieu historique, germe de la passion pour le football dans la capitale biscayenne et origine du c\u00e9l\u00e8bre Athletic Club.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Campa de los Ingleses (Le Terrain des Anglais) \u00e0 Bilbao | Visit San Mames\" \/>\n<meta property=\"og:description\" content=\"La Campa de los Ingleses \u00e0 Bilbao est un lieu historique, germe de la passion pour le football dans la capitale biscayenne et origine du c\u00e9l\u00e8bre Athletic Club.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/\" \/>\n<meta property=\"og:site_name\" content=\"San Mam\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-11T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-24T10:52:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2022\/05\/campa-ingleses-bilbao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"woko-sanmames\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"woko-sanmames\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/terrain-des-anglais-bilbao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/terrain-des-anglais-bilbao\\\/\"},\"author\":{\"name\":\"woko-sanmames\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/ce85ff13ba5a5d52e8964e9b82b5dc8f\"},\"headline\":\"La Campa de los Ingleses (Le Terrain des Anglais) \u00e0 Bilbao\",\"datePublished\":\"2019-03-11T23:00:00+00:00\",\"dateModified\":\"2023-01-24T10:52:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/terrain-des-anglais-bilbao\\\/\"},\"wordCount\":530,\"image\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/terrain-des-anglais-bilbao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/campa-ingleses-bilbao.jpg\",\"keywords\":[\"mejores sitios bilbao\",\"paseo por bilbao\"],\"articleSection\":[\"Visiter Bilbao\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/terrain-des-anglais-bilbao\\\/\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/terrain-des-anglais-bilbao\\\/\",\"name\":\"La Campa de los Ingleses (Le Terrain des Anglais) \u00e0 Bilbao | Visit San Mames\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/terrain-des-anglais-bilbao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/terrain-des-anglais-bilbao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/campa-ingleses-bilbao.jpg\",\"datePublished\":\"2019-03-11T23:00:00+00:00\",\"dateModified\":\"2023-01-24T10:52:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/ce85ff13ba5a5d52e8964e9b82b5dc8f\"},\"description\":\"La Campa de los Ingleses \u00e0 Bilbao est un lieu historique, germe de la passion pour le football dans la capitale biscayenne et origine du c\u00e9l\u00e8bre Athletic Club.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/terrain-des-anglais-bilbao\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/terrain-des-anglais-bilbao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/terrain-des-anglais-bilbao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/campa-ingleses-bilbao.jpg\",\"contentUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/campa-ingleses-bilbao.jpg\",\"width\":1300,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/terrain-des-anglais-bilbao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Campa de los Ingleses (Le Terrain des Anglais) \u00e0 Bilbao\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#website\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/\",\"name\":\"San Mam\u00e9s\",\"description\":\"Conoce San Mames VIP Area y descubre todos los servicios de los que puedes disfrutar durante un partido o cuando celebres un evento de empresa.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/ce85ff13ba5a5d52e8964e9b82b5dc8f\",\"name\":\"woko-sanmames\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ed6d82ec86db15ff8aaa7ad2994dd8d485edfa2a12260fbba4bcb2729f27f81?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ed6d82ec86db15ff8aaa7ad2994dd8d485edfa2a12260fbba4bcb2729f27f81?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ed6d82ec86db15ff8aaa7ad2994dd8d485edfa2a12260fbba4bcb2729f27f81?s=96&d=mm&r=g\",\"caption\":\"woko-sanmames\"},\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/author\\\/woko-sanmames\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Campa de los Ingleses (Le Terrain des Anglais) \u00e0 Bilbao | Visit San Mames","description":"La Campa de los Ingleses \u00e0 Bilbao est un lieu historique, germe de la passion pour le football dans la capitale biscayenne et origine du c\u00e9l\u00e8bre Athletic Club.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/","og_locale":"fr_FR","og_type":"article","og_title":"La Campa de los Ingleses (Le Terrain des Anglais) \u00e0 Bilbao | Visit San Mames","og_description":"La Campa de los Ingleses \u00e0 Bilbao est un lieu historique, germe de la passion pour le football dans la capitale biscayenne et origine du c\u00e9l\u00e8bre Athletic Club.","og_url":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/","og_site_name":"San Mam\u00e9s","article_published_time":"2019-03-11T23:00:00+00:00","article_modified_time":"2023-01-24T10:52:48+00:00","og_image":[{"width":1300,"height":655,"url":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2022\/05\/campa-ingleses-bilbao.jpg","type":"image\/jpeg"}],"author":"woko-sanmames","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"woko-sanmames"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/#article","isPartOf":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/"},"author":{"name":"woko-sanmames","@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/ce85ff13ba5a5d52e8964e9b82b5dc8f"},"headline":"La Campa de los Ingleses (Le Terrain des Anglais) \u00e0 Bilbao","datePublished":"2019-03-11T23:00:00+00:00","dateModified":"2023-01-24T10:52:48+00:00","mainEntityOfPage":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/"},"wordCount":530,"image":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/#primaryimage"},"thumbnailUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2022\/05\/campa-ingleses-bilbao.jpg","keywords":["mejores sitios bilbao","paseo por bilbao"],"articleSection":["Visiter Bilbao"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/","url":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/","name":"La Campa de los Ingleses (Le Terrain des Anglais) \u00e0 Bilbao | Visit San Mames","isPartOf":{"@id":"https:\/\/sanmames.athletic-club.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/#primaryimage"},"image":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/#primaryimage"},"thumbnailUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2022\/05\/campa-ingleses-bilbao.jpg","datePublished":"2019-03-11T23:00:00+00:00","dateModified":"2023-01-24T10:52:48+00:00","author":{"@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/ce85ff13ba5a5d52e8964e9b82b5dc8f"},"description":"La Campa de los Ingleses \u00e0 Bilbao est un lieu historique, germe de la passion pour le football dans la capitale biscayenne et origine du c\u00e9l\u00e8bre Athletic Club.","breadcrumb":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/#primaryimage","url":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2022\/05\/campa-ingleses-bilbao.jpg","contentUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2022\/05\/campa-ingleses-bilbao.jpg","width":1300,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/terrain-des-anglais-bilbao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sanmames.athletic-club.eus\/fr\/"},{"@type":"ListItem","position":2,"name":"La Campa de los Ingleses (Le Terrain des Anglais) \u00e0 Bilbao"}]},{"@type":"WebSite","@id":"https:\/\/sanmames.athletic-club.eus\/#website","url":"https:\/\/sanmames.athletic-club.eus\/","name":"San Mam\u00e9s","description":"Conoce San Mames VIP Area y descubre todos los servicios de los que puedes disfrutar durante un partido o cuando celebres un evento de empresa.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sanmames.athletic-club.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/ce85ff13ba5a5d52e8964e9b82b5dc8f","name":"woko-sanmames","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8ed6d82ec86db15ff8aaa7ad2994dd8d485edfa2a12260fbba4bcb2729f27f81?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ed6d82ec86db15ff8aaa7ad2994dd8d485edfa2a12260fbba4bcb2729f27f81?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ed6d82ec86db15ff8aaa7ad2994dd8d485edfa2a12260fbba4bcb2729f27f81?s=96&d=mm&r=g","caption":"woko-sanmames"},"url":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/author\/woko-sanmames\/"}]}},"_links":{"self":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/5700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/users\/293"}],"replies":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/comments?post=5700"}],"version-history":[{"count":5,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/5700\/revisions"}],"predecessor-version":[{"id":9601,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/5700\/revisions\/9601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/media\/5276"}],"wp:attachment":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/media?parent=5700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/categories?post=5700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/tags?post=5700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}