{"id":24105,"date":"2026-06-17T07:00:00","date_gmt":"2026-06-17T05:00:00","guid":{"rendered":"https:\/\/sanmames.athletic-club.eus\/?p=24105"},"modified":"2026-06-04T11:41:06","modified_gmt":"2026-06-04T09:41:06","slug":"route-des-fresques-bilbao-art-urbain","status":"publish","type":"post","link":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/route-des-fresques-bilbao-art-urbain\/","title":{"rendered":"Circuit des fresques murales \u00e0 Bilbao : d\u00e9couvrez le meilleur de l\u2019art urbain de la ville"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les murs de Bilbao ne se contentent plus de porter le poids de son pass\u00e9 industriel ; aujourd\u2019hui, ils parlent, chantent et racontent l\u2019\u00e2me d\u2019une ville en constante transformation. Ce qui a commenc\u00e9 comme des expressions spontan\u00e9es dans des recoins oubli\u00e9s est devenu l\u2019une des grandes attractions culturelles de la ville. Pour planifier un parcours \u00e0 la d\u00e9couverte <strong>de l\u2019art urbain \u00e0 Bilbao<\/strong>, il faut lever les yeux de la carte habituelle et se laisser surprendre. C\u2019est une exp\u00e9rience culturelle id\u00e9ale \u00e0 vivre \u00e0 pied t\u00f4t le matin ou au coucher du soleil \u2014 lorsque la lumi\u00e8re est parfaite pour la photographie \u2014, en profitant du confort du r\u00e9seau urbain et en savourant les \u00e9tablissements gastronomiques qui se pr\u00e9sentent sur votre chemin.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le fleuve comme toile : l\u2019h\u00e9ritage ouvrier et les nouveaux g\u00e9ants <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019eau a toujours \u00e9t\u00e9 le moteur de Bilbao, et ses berges constituent le point de d\u00e9part id\u00e9al pour un parcours visuel de grande envergure. La promenade qui relie le pont de Deusto \u00e0 l\u2019\u00eele de <strong>Zorrozaurre <\/strong>rassemble certaines des fresques murales grand format les plus impressionnantes, int\u00e9gr\u00e9es \u00e0 d\u2019anciennes structures industrielles. En suivant le cours du fleuve vers Zorroza et Olabeaga, les tons verts et bleus envahissent les murs pour faire revivre la <strong>m\u00e9moire portuaire et ouvri\u00e8re <\/strong>\u00e0 travers une esth\u00e9tique navale saisissante. Dans ce quartier, on remarque l\u2019imposante intervention urbaine <strong><em>\u00ab So\u00f1ar \u00bb (R\u00eaver) <\/em>de SpY \u00e0 Olabeaga<\/strong>, une proposition conceptuelle de lettres g\u00e9antes qui dialogue directement avec la transformation urbaine du quartier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En p\u00e9n\u00e9trant au c\u0153ur de la ville, les contrastes architecturaux de l\u2019Ensanche et le charme des Siete Calles r\u00e9v\u00e8lent des formes d\u2019art urbain beaucoup plus intimes. Alors que la Gran V\u00eda et ses rues adjacentes abritent des fresques murales au design corporate int\u00e9gr\u00e9es aux fa\u00e7ades commerciales, le <strong>Casco Viejo <\/strong>et les passages proches de La Ribera se remplissent de pochoirs, de typographies et de collages regorgeant de messages culturels.&nbsp;Des \u0153uvres reconnues telles que <strong><em>\u00ab Giltza Bat \u00bb (une cl\u00e9)<\/em>, <\/strong>r\u00e9alis\u00e9e par Ver\u00f3nica et Christina Werckmeister sous le pont de La Salve, ou la peinture \u00e9mouvante d\u00e9di\u00e9e aux <strong><em>\u00abSupervivientes de la violencia machista \u00bb (Survivantes de la violence machiste) <\/em>de Ruth Juan <\/strong>sur le quai de La Merced, d\u00e9montrent que les murs de Bilbao agissent comme un porte-voix social engag\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Trois circuits incontournables pour d\u00e9couvrir les fresques murales de Bilbao<em>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/em><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&nbsp;1. <\/em><strong><em>Deusto &#8211; Zorrozaurre &#8211; Olabeaga. <\/em><\/strong><em>Ambiance portuaire et \u0153uvres&nbsp;<em>de grand format int\u00e9gr\u00e9es au paysage industriel.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/em>&nbsp;&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&nbsp;2. <\/em><strong><em>Casco Viejo &#8211; Ensanche. <\/em><\/strong><em>Pochoirs sur volets, passages&nbsp;&nbsp;avec des typographies et des fresques au design moderne.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&nbsp;3. <\/em><strong><em>Santutxu &#8211; San Francisco &#8211; Recalde.<\/em><\/strong> <em>Couleurs communautaires,&nbsp;&nbsp;r\u00e9cits sociaux intenses et places avec des points de vue photographiques.&nbsp;<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Art urbain dans les quartiers de Bilbao : couleur, avant-garde et r\u00e9cit <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Monter vers Santutxu, Bego\u00f1a ou San Francisco, c\u2019est s\u2019immerger dans la facette la plus vivante, communautaire et parfois transgressive de <strong>l\u2019art urbain \u00e0 Bilbao<\/strong>. Un parcours dans ces quartiers impose des arr\u00eats incontournables devant des \u0153uvres internationales de premier plan, comme le collage <strong><em>\u00ab Futurismo Primitivo \u00bb (Futurisme primitif) <\/em><\/strong><strong>de Sixe Paredes <\/strong>ou <strong><em>\u00ab El fin justificado \u00bb (La fin justifi\u00e9e) <\/em><\/strong><strong>d\u2019Aryz <\/strong>\u00e0 Bilbao La Vieja. Le parcours s\u2019enrichit de la force \u00e9motionnelle de l\u2019intervention de <strong>SUSO33 <\/strong>dans la rue Concepci\u00f3n ou de la mosa\u00efque vibrante de la <strong>Plaza Kiriki\u00f1o \u00e0 Iralabarri<\/strong>, des espaces o\u00f9 la rue devient un lieu de rencontre et de r\u00e9flexion.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019art dans les quartiers de Bilbao sert de pont pour le dialogue interculturel ; les fa\u00e7ades ne se contentent pas de d\u00e9corer, elles revendiquent les racines, la lutte sociale et les espoirs du quartier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce ph\u00e9nom\u00e8ne doit en grande partie \u00e0 l\u2019\u00e9lan donn\u00e9 par des festivals tels que le <strong>Bilbao Margo Festival <\/strong>et \u00e0 l\u2019implication de cr\u00e9ateurs locaux et internationaux qui ont r\u00e9invent\u00e9 le paysage de la Biscaye. Des artistes tels que <strong>J. Maier<\/strong>, avec son mysticisme introspectif, ou <strong>Marta Mena <\/strong>et ses imposantes figures du quotidien, partagent la vedette avec des figures de proue telles <strong>qu\u2019Okuda San Miguel<\/strong>, auteur de l\u2019explosive et g\u00e9om\u00e9trique <strong><em>\u00ab Cara de la Cultura \u00bb (Le visage de la culture) <\/em><\/strong>\u00e0 Abando. La fusion des styles se respire \u00e9galement dans des \u0153uvres collectives telles que <strong><em>\u00ab La Flor de la Vida \u00bb (La Fleur de la Vie) <\/em><\/strong>\u00e0 Recalde, symbole du renouveau printanier, ou dans les \u0153uvres de fantaisie naturelle cr\u00e9\u00e9es par <strong>Dulk<\/strong>, auteur du c\u00e9l\u00e8bre <strong><em>\u00ab Unicornio de Santutxu \u00bb (L\u2019Unicorne de Santutxu) <\/em><\/strong>qui invite \u00e0 la r\u00eaverie entre les immeubles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les fresques murales de l\u2019Athletic Club : le football comme art du terroir <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il est impossible de comprendre la culture de la Biscaye sans l\u2019ombre allong\u00e9e de l\u2019Athletic Club, un sentiment qui impr\u00e8gne naturellement les <strong>fresques murales de Bilbao <\/strong>et de ses environs. Les murs font office d\u2019autels la\u00efques rendant hommage aux l\u00e9gendes et \u00e0 la mythologie m\u00eame du club, un ancrage historique que les passionn\u00e9s de football peuvent \u00e9galement explorer en profondeur en visitant les expositions de <a href=\"https:\/\/tickets.athletic-club.eus\/athleticclub-museo\/events?utm_source=sanmames.athletic-club.eus\/blog&amp;utm_medium=referral&amp;utm_campaign=actualidad&amp;utm_content=route-des-fresques-bilbao-art-urbain\"><strong>l\u2019AC Museoa<\/strong><\/a><strong>.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans la r\u00e9gion m\u00e9tropolitaine, la <a href=\"https:\/\/www.google.com\/search?q=https:\/\/mapas.uribe.eu\/es\/mapa-de-uribe\/resource\/r\/mural-lamiako%231779370942885\"><strong>f<\/strong><\/a><a href=\"https:\/\/mapas.uribe.eu\/es\/mapa-de-uribe\/resource\/r\/mural-lamiako#1780046564302?utm_source=sanmames.athletic-club.eus\/BLOG&amp;utm_medium=referral&amp;utm_campaign=ecosistema-ac&amp;utm_content=ruta-de-murales-en-bilbao:-descubre-el-mejor-arte-urbano-de-la-ciudad\"><strong>resque \u00e9mouvante de l\u2019Athletic \u00e0 Lamiako<\/strong><\/a>, un site historique incontournable, se distingue particuli\u00e8rement. C\u2019est pr\u00e9cis\u00e9ment sur les anciens terrains mar\u00e9cageux de Lamiako, o\u00f9 se trouvait \u00e0 l\u2019origine un hippodrome, que le club rouge et blanc a forg\u00e9 ses premiers exploits footballistiques avant la construction de l\u2019embl\u00e9matique \u00ab Cath\u00e9drale \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inaugur\u00e9e \u00e0 l\u2019occasion de l\u2019anniversaire du club sur le terrain de futsal local, cette grande fresque repr\u00e9sente les pionniers du ballon rond v\u00eatus de la tenue historique bleu et blanc des d\u00e9buts, flanqu\u00e9s de panneaux explicatifs qui mettent en lumi\u00e8re le lien indissoluble entre Lamiako et la naissance du football basque. Ce respect pour l\u2019h\u00e9ritage est compl\u00e9t\u00e9 par des t\u00e9moignages de l\u2019histoire contemporaine du club, comme la c\u00e9l\u00e8bre <a href=\"https:\/\/www.athletic-club.eus\/noticias\/2025\/06\/27\/nico-williams-recupera-su-lugar-en-el-mural\/?utm_source=sanmames.athletic-club.eus\/BLOG&amp;utm_medium=referral&amp;utm_campaign=ecosistema-ac&amp;utm_content=ruta-de-murales-en-bilbao:-descubre-el-mejor-arte-urbano-de-la-ciudad\"><strong>fresque des fr\u00e8res Williams<\/strong><\/a> et Muniain, \u00e0 laquelle se sont ajout\u00e9s d\u2019autres grands joueurs de l\u2019Athletic Club, situ\u00e9e dans le quartier voisin de Lutxana. L\u2019\u0153uvre, r\u00e9alis\u00e9e par l\u2019artiste <strong>Carlos L\u00f3pez (Kicking Art) <\/strong>pour comm\u00e9morer le vingt-cinqui\u00e8me titre de Coupe, est devenue un v\u00e9ritable barom\u00e8tre social et un lieu de p\u00e8lerinage incontournable qui d\u00e9montre que l\u2019art de rue, en terre biscayenne, s\u2019\u00e9crit avec la passion rouge et blanche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&nbsp;&nbsp;&nbsp;&nbsp;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les murs de Bilbao ne se contentent plus de porter le poids de son pass\u00e9 industriel ; aujourd\u2019hui, ils parlent, chantent et racontent l\u2019\u00e2me d\u2019une ville en constante transformation. Ce qui a commenc\u00e9 comme des expressions spontan\u00e9es dans des recoins oubli\u00e9s est devenu l\u2019une des grandes attractions culturelles de la ville. Pour planifier un parcours [&hellip;]<\/p>\n","protected":false},"author":298,"featured_media":23952,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[289,73],"tags":[],"class_list":["post-24105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-san-mames","category-visiter-bilbao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Circuit des fresques murales \u00e0 Bilbao : le meilleur de l\u2019art urbain de la ville<\/title>\n<meta name=\"description\" content=\"Explorez le parcours des fresques murales \u00e0 Bilbao. Un guide d\u2019art urbain \u00e0 travers le Casco Viejo, le Fleuve et les quartiers, incluant la fresque historique de l\u2019Athletic \u00e0 Lamiako.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sanmames.athletic-club.eus\/?p=23947\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Circuit des fresques murales \u00e0 Bilbao : le meilleur de l\u2019art urbain de la ville\" \/>\n<meta property=\"og:description\" content=\"Explorez le parcours des fresques murales \u00e0 Bilbao. Un guide d\u2019art urbain \u00e0 travers le Casco Viejo, le Fleuve et les quartiers, incluant la fresque historique de l\u2019Athletic \u00e0 Lamiako.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sanmames.athletic-club.eus\/?p=23947\" \/>\n<meta property=\"og:site_name\" content=\"San Mam\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-17T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2026\/05\/Copia-de-imagenes-para-blog-64-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"seo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"seo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?p=23947#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?p=23947\"},\"author\":{\"name\":\"seo\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/ea759abc8515866a1b0ac6c7576bd9fb\"},\"headline\":\"Circuit des fresques murales \u00e0 Bilbao : d\u00e9couvrez le meilleur de l\u2019art urbain de la ville\",\"datePublished\":\"2026-06-17T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?p=23947\"},\"wordCount\":1194,\"image\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?p=23947#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Copia-de-imagenes-para-blog-64.png\",\"articleSection\":[\"Tour San Mames\",\"Visiter Bilbao\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?p=23947\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?p=23947\",\"name\":\"Circuit des fresques murales \u00e0 Bilbao : le meilleur de l\u2019art urbain de la ville\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?p=23947#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?p=23947#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Copia-de-imagenes-para-blog-64.png\",\"datePublished\":\"2026-06-17T05:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/ea759abc8515866a1b0ac6c7576bd9fb\"},\"description\":\"Explorez le parcours des fresques murales \u00e0 Bilbao. Un guide d\u2019art urbain \u00e0 travers le Casco Viejo, le Fleuve et les quartiers, incluant la fresque historique de l\u2019Athletic \u00e0 Lamiako.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?p=23947#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?p=23947\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?p=23947#primaryimage\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Copia-de-imagenes-para-blog-64.png\",\"contentUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Copia-de-imagenes-para-blog-64.png\",\"width\":2240,\"height\":1260,\"caption\":\"ruta-murales-bilbao-arte-urbano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?p=23947#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Circuit des fresques murales \u00e0 Bilbao : d\u00e9couvrez le meilleur de l\u2019art urbain de la ville\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#website\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/\",\"name\":\"San Mam\u00e9s\",\"description\":\"Conoce San Mames VIP Area y descubre todos los servicios de los que puedes disfrutar durante un partido o cuando celebres un evento de empresa.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/ea759abc8515866a1b0ac6c7576bd9fb\",\"name\":\"seo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/992ca0800ab154d480e9f85761aec6161348fe0ea85dfc6c0e3907a61f714cc3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/992ca0800ab154d480e9f85761aec6161348fe0ea85dfc6c0e3907a61f714cc3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/992ca0800ab154d480e9f85761aec6161348fe0ea85dfc6c0e3907a61f714cc3?s=96&d=mm&r=g\",\"caption\":\"seo\"},\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/author\\\/seo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Circuit des fresques murales \u00e0 Bilbao : le meilleur de l\u2019art urbain de la ville","description":"Explorez le parcours des fresques murales \u00e0 Bilbao. Un guide d\u2019art urbain \u00e0 travers le Casco Viejo, le Fleuve et les quartiers, incluant la fresque historique de l\u2019Athletic \u00e0 Lamiako.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sanmames.athletic-club.eus\/?p=23947","og_locale":"fr_FR","og_type":"article","og_title":"Circuit des fresques murales \u00e0 Bilbao : le meilleur de l\u2019art urbain de la ville","og_description":"Explorez le parcours des fresques murales \u00e0 Bilbao. Un guide d\u2019art urbain \u00e0 travers le Casco Viejo, le Fleuve et les quartiers, incluant la fresque historique de l\u2019Athletic \u00e0 Lamiako.","og_url":"https:\/\/sanmames.athletic-club.eus\/?p=23947","og_site_name":"San Mam\u00e9s","article_published_time":"2026-06-17T05:00:00+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2026\/05\/Copia-de-imagenes-para-blog-64-1024x576.png","type":"image\/png"}],"author":"seo","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"seo","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sanmames.athletic-club.eus\/?p=23947#article","isPartOf":{"@id":"https:\/\/sanmames.athletic-club.eus\/?p=23947"},"author":{"name":"seo","@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/ea759abc8515866a1b0ac6c7576bd9fb"},"headline":"Circuit des fresques murales \u00e0 Bilbao : d\u00e9couvrez le meilleur de l\u2019art urbain de la ville","datePublished":"2026-06-17T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/sanmames.athletic-club.eus\/?p=23947"},"wordCount":1194,"image":{"@id":"https:\/\/sanmames.athletic-club.eus\/?p=23947#primaryimage"},"thumbnailUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2026\/05\/Copia-de-imagenes-para-blog-64.png","articleSection":["Tour San Mames","Visiter Bilbao"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sanmames.athletic-club.eus\/?p=23947","url":"https:\/\/sanmames.athletic-club.eus\/?p=23947","name":"Circuit des fresques murales \u00e0 Bilbao : le meilleur de l\u2019art urbain de la ville","isPartOf":{"@id":"https:\/\/sanmames.athletic-club.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sanmames.athletic-club.eus\/?p=23947#primaryimage"},"image":{"@id":"https:\/\/sanmames.athletic-club.eus\/?p=23947#primaryimage"},"thumbnailUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2026\/05\/Copia-de-imagenes-para-blog-64.png","datePublished":"2026-06-17T05:00:00+00:00","author":{"@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/ea759abc8515866a1b0ac6c7576bd9fb"},"description":"Explorez le parcours des fresques murales \u00e0 Bilbao. Un guide d\u2019art urbain \u00e0 travers le Casco Viejo, le Fleuve et les quartiers, incluant la fresque historique de l\u2019Athletic \u00e0 Lamiako.","breadcrumb":{"@id":"https:\/\/sanmames.athletic-club.eus\/?p=23947#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sanmames.athletic-club.eus\/?p=23947"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sanmames.athletic-club.eus\/?p=23947#primaryimage","url":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2026\/05\/Copia-de-imagenes-para-blog-64.png","contentUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2026\/05\/Copia-de-imagenes-para-blog-64.png","width":2240,"height":1260,"caption":"ruta-murales-bilbao-arte-urbano"},{"@type":"BreadcrumbList","@id":"https:\/\/sanmames.athletic-club.eus\/?p=23947#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sanmames.athletic-club.eus\/fr\/"},{"@type":"ListItem","position":2,"name":"Circuit des fresques murales \u00e0 Bilbao : d\u00e9couvrez le meilleur de l\u2019art urbain de la ville"}]},{"@type":"WebSite","@id":"https:\/\/sanmames.athletic-club.eus\/#website","url":"https:\/\/sanmames.athletic-club.eus\/","name":"San Mam\u00e9s","description":"Conoce San Mames VIP Area y descubre todos los servicios de los que puedes disfrutar durante un partido o cuando celebres un evento de empresa.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sanmames.athletic-club.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/ea759abc8515866a1b0ac6c7576bd9fb","name":"seo","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/992ca0800ab154d480e9f85761aec6161348fe0ea85dfc6c0e3907a61f714cc3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/992ca0800ab154d480e9f85761aec6161348fe0ea85dfc6c0e3907a61f714cc3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/992ca0800ab154d480e9f85761aec6161348fe0ea85dfc6c0e3907a61f714cc3?s=96&d=mm&r=g","caption":"seo"},"url":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/author\/seo\/"}]}},"_links":{"self":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/24105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/users\/298"}],"replies":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/comments?post=24105"}],"version-history":[{"count":3,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/24105\/revisions"}],"predecessor-version":[{"id":24116,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/24105\/revisions\/24116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/media\/23952"}],"wp:attachment":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/media?parent=24105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/categories?post=24105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/tags?post=24105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}