{"id":19702,"date":"2025-11-26T16:40:51","date_gmt":"2025-11-26T15:40:51","guid":{"rendered":"https:\/\/sanmames.athletic-club.eus\/?p=19702"},"modified":"2025-11-26T16:44:54","modified_gmt":"2025-11-26T15:44:54","slug":"4-jours-a-bilbao-itineraire-et-sites-a-visiter","status":"publish","type":"post","link":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/","title":{"rendered":"4 jours \u00e0 Bilbao : itin\u00e9raire et sites \u00e0 visiter"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><p class='entradilla'>Vous disposez de 4 jours pour visiter Bilbao et ses environs ? Vous avez de la chance ! C\u2019est largement suffisant pour profiter de cette ville anim\u00e9e et de ses nombreux tr\u00e9sors \u00e0 proximit\u00e9. La capitale de la Biscaye vous surprendra par son m\u00e9lange parfait d\u2019art contemporain, de vestiges du pass\u00e9, de gastronomie d\u2019avant-garde et de paysages verdoyants \u00e0 couper le souffle.<\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oubliez la pr\u00e9cipitation : nous vous proposons un itin\u00e9raire qui combine ville et nature, ainsi qu\u2019une immersion dans l\u2019ambiance de Bilbao. Pr\u00e9parez de bonnes chaussures, et en route !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Jour 1 : Le c\u0153ur de Bilbao : Guggenheim, Casco Viejo, Artxanda<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Guggenheim :<\/strong><strong> l\u2019ic\u00f4ne de l\u2019art moderne<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Commencez votre aventure au c\u0153ur culturel de la ville, dans l\u2019un des lieux embl\u00e9matiques de Bilbao : le <strong>Mus\u00e9e Guggenheim<\/strong>, une sculpture titanesque en titane con\u00e7ue par Frank Gehry qui a transform\u00e9 la capitale de la Biscaye en une destination touristique de premier plan depuis son inauguration en 1997.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consacrez votre matin\u00e9e \u00e0 la visite des expositions temporaires et des installations permanentes, telles que l\u2019embl\u00e9matique \u00ab Puppy \u00bb, le chien g\u00e9ant recouvert de fleurs qui accueille les visiteurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Casco Viejo : les meilleurs pintxos de Bilbao<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 midi, rendez-vous dans le Casco Viejo (la vieille ville), un labyrinthe de sept rues o\u00f9 Bilbao a vu le jour. N\u2019oubliez pas de visiter la Plaza Nueva, qui regorge de pintxos basques traditionnels. Et n&#8217;oubliez pas de go\u00fbter la \u00ab gilda \u00bb (pintxo \u00e0 base d\u2019anchois, de piment et d\u2019olive) !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Artxanda : le belv\u00e9d\u00e8re panoramique de Bilbao<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Passez l\u2019apr\u00e8s-midi \u00e0 faire vos adieux \u00e0 Bilbao en beaut\u00e9. Et quand nous disons \u00ab en beaut\u00e9 \u00bb, ce n\u2019est pas seulement une expression. Prenez le <strong>funiculaire d\u2019Artxanda<\/strong> pour monter au sommet de cette colline, d\u2019o\u00f9 vous pourrez profiter des meilleures vues panoramiques sur la ville et le fleuve.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Jour 2 : Voyage sur la c\u00f4te basque : Getxo et Sopelana<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Getxo : <\/strong>promenade maritime et charme c\u00f4tier<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prenez le m\u00e9tro (ligne 1) jusqu\u2019\u00e0 Getxo, une localit\u00e9 situ\u00e9e \u00e0 seulement 20 minutes de Bilbao. Explorez le vieux port de Getxo, class\u00e9 bien d\u2019int\u00e9r\u00eat culturel, puis rendez-vous \u00e0 la plage d\u2019Ereaga, o\u00f9 vous pourrez d\u00e9guster un excellent menu dans l\u2019un des restaurants du quartier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sopelana: <\/strong>plages et falaises de r\u00eave<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans l\u2019apr\u00e8s-midi, reprenez le m\u00e9tro et rendez-vous \u00e0 Sopelana, \u00e0 seulement 10 minutes de Getxo, pour vous promener sur la plage de Sopelana, l\u2019une des plus belles du Pays Basque, et profiter d\u2019une vue imprenable sur la c\u00f4te bisca\u00efenne.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Jour 3 : San Mam\u00e9s et la v\u00e9ritable atmosph\u00e8re de Bilbao<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L\u2019AC Museoa et le Tour San Mam\u00e9s: <\/strong>histoire, \u00e9motion et football<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bilbao vit au rythme de l\u2019Athletic Club, qui est plus qu\u2019une simple \u00e9quipe de football, c\u2019est tout un sentiment. Si possible, planifiez votre visite \u00e0 Bilbao de mani\u00e8re \u00e0 assister \u00e0 un match \u00e0 domicile des Lions et \u00e0 ressentir l\u2019ambiance incomparable d\u2019une rencontre \u00e0 San Mam\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous vous invitons \u00e9galement \u00e0 visiter l\u2019<strong><a href=\"https:\/\/www.athletic-club.eus\/en\/tickets\/?utm_source=sanmames.athletic-club.eus\/blog&amp;utm_medium=referral&amp;utm_campaign=actualidad&amp;utm_content=4-jours-a-bilbao-itineraire-et-sites-a-visiter\" target=\"_blank\" rel=\"noreferrer noopener\">AC Museoa<\/a><\/strong>, le mus\u00e9e de l\u2019Athletic Club, un lieu interactif qui retrace plus de 125 ans d\u2019histoire des Lions \u00e0 travers leurs troph\u00e9es, leurs anciens \u00e9quipements&#8230; et vous permettra de d\u00e9couvrir ce qui rend ce club si sp\u00e9cial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Compl\u00e9tez votre visite du mus\u00e9e par le <strong><a href=\"https:\/\/www.athletic-club.eus\/en\/tickets\/?utm_source=sanmames.athletic-club.eus\/blog&amp;utm_medium=referral&amp;utm_campaign=actualidad&amp;utm_content=4-jours-a-bilbao-itineraire-et-sites-a-visiter\" target=\"_blank\" rel=\"noreferrer noopener\">Tour San Mames<\/a><\/strong>, qui vous permettra de d\u00e9couvrir les vestiaires, le tunnel des joueurs, la pelouse ou la salle de presse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acc\u00e9dez \u00e0 l\u2019AC Museoa et au Tour San Mam\u00e9s par les portes 19 et 20 du stade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Boutique officielle et gastronomie \u00e0 San Mam\u00e9s<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u2019oubliez pas d\u2019acheter un souvenir rouge et blanc dans la boutique de l\u2019Athletic situ\u00e9e \u00e0 San Mam\u00e9s, entre les portes 26 et 0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et ne vous inqui\u00e9tez pas, vous n\u2019aurez pas \u00e0 vous demander o\u00f9 manger, car dans le stade m\u00eame, vous aurez la possibilit\u00e9 de d\u00e9guster le meilleur menu dans nos trois restaurants : <strong><a href=\"https:\/\/sanmamesjatetxea.com\/?lang=en&amp;utm_source=sanmames.athletic-club.eus\/blog&amp;utm_medium=referral&amp;utm_campaign=actualidad&amp;utm_content=4-jours-a-bilbao-itineraire-et-sites-a-visiter\" target=\"_blank\" rel=\"noreferrer noopener\">San Mames Jatetxea<\/a>, <a href=\"https:\/\/es.lacampadelosingleses.com\/?utm_source=sanmames.athletic-club.eus\/blog&amp;utm_medium=referral&amp;utm_campaign=actualidad&amp;utm_content=4-jours-a-bilbao-itineraire-et-sites-a-visiter\" target=\"_blank\" rel=\"noreferrer noopener\">La Campa de los Ingleses<\/a> ou <a href=\"https:\/\/geuriasanmames.com\/?utm_source=sanmames.athletic-club.eus\/blog&amp;utm_medium=referral&amp;utm_campaign=actualidad&amp;utm_content=4-jours-a-bilbao-itineraire-et-sites-a-visiter\" target=\"_blank\" rel=\"noreferrer noopener\">Geuria!<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Jour 4 : Excursion \u00e0 San Juan de Gaztelugatxe<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">S\u2019il existe un lieu qui symbolise la magie du Pays Basque, c\u2019est bien <strong>San Juan de Gaztelugatxe<\/strong>, une chapelle construite sur un \u00eelot rocheux, reli\u00e9e au continent par 241 marches qui semblent flotter sur la mer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis Bilbao, roulez environ 35 km jusqu\u2019\u00e0 <strong>Bermeo<\/strong> et suivez les panneaux indiquant le parking de Gaztelugatxe. Le chemin jusqu\u2019au sommet dure environ 30 minutes, mais la vue sur la mer Cantabrique vous laissera bouche b\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une fois arriv\u00e9 au sommet, veuillez <strong>sonner trois fois la cloche et faire un v\u0153u<\/strong>, comme le veut la tradition.<br>Les amateurs de <em>Game of Thrones<\/em> reconna\u00eetront cet endroit : il a servi de d\u00e9cor \u00e0 <strong>Dragonstone<\/strong>, la forteresse de Daenerys Targaryen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avant de regagner Bilbao, faites une halte \u00e0 <strong>Bermeo<\/strong> ou <strong>Bakio<\/strong> pour d\u00e9guster du poisson frais ou savourer un verre de <strong>txakoli<\/strong>, le vin blanc local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prenez note et vivez 4 jours incomparables \u00e0 Bilbao et dans ses environs, avec une touche rouge et blanche incontournable ! Et si vous ne disposez que d\u2019une seule journ\u00e9e&#8230; ne vous inqui\u00e9tez pas ! Voici notre programme id\u00e9al pour <a href=\"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/bilbao-en-une-journee-le-meilleur-itineraire-express\/?utm_source=sanmames.athletic-club.eus\/blog&#038;utm_medium=referral&#038;utm_campaign=actualidad&#038;utm_content=4-jours-a-bilbao-itineraire-et-sites-a-visiter\"><strong>profiter de Bilbao en seulement 24 heures<\/strong> !<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oubliez la pr\u00e9cipitation : nous vous proposons un itin\u00e9raire qui combine ville et nature, ainsi qu\u2019une immersion dans l\u2019ambiance de Bilbao. Pr\u00e9parez de bonnes chaussures, et en route ! Jour 1 : Le c\u0153ur de Bilbao : Guggenheim, Casco Viejo, Artxanda Guggenheim : l\u2019ic\u00f4ne de l\u2019art moderne Commencez votre aventure au c\u0153ur culturel de la [&hellip;]<\/p>\n","protected":false},"author":296,"featured_media":19345,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[73],"tags":[261,254,226,366],"class_list":["post-19702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-visiter-bilbao","tag-athletic-club-fr","tag-mejores-sitios-bilbao-fr","tag-san-mames-fr","tag-visit-bilbao-fr-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 jours \u00e0 Bilbao : itin\u00e9raire et sites \u00e0 visiter<\/title>\n<meta name=\"description\" content=\"Vous disposez de 4 jours pour visiter Bilbao et ses environs ? Vous avez de la chance ! C\u2019est largement suffisant pour profiter de cette ville anim\u00e9e\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 jours \u00e0 Bilbao : itin\u00e9raire et sites \u00e0 visiter\" \/>\n<meta property=\"og:description\" content=\"Vous disposez de 4 jours pour visiter Bilbao et ses environs ? Vous avez de la chance ! C\u2019est largement suffisant pour profiter de cette ville anim\u00e9e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/\" \/>\n<meta property=\"og:site_name\" content=\"San Mam\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-26T15:40:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T15:44:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2025\/11\/sanmames-4-dias-en-bilbao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Visit San Mames Athletic Club\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Visit San Mames Athletic Club\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\\\/\"},\"author\":{\"name\":\"Blog Visit San Mames Athletic Club\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/bd9f448a07934bf59af8b87821025bbc\"},\"headline\":\"4 jours \u00e0 Bilbao : itin\u00e9raire et sites \u00e0 visiter\",\"datePublished\":\"2025-11-26T15:40:51+00:00\",\"dateModified\":\"2025-11-26T15:44:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\\\/\"},\"wordCount\":877,\"image\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/sanmames-4-dias-en-bilbao.jpg\",\"keywords\":[\"athletic club\",\"mejores sitios bilbao\",\"san mam\u00e9s\",\"Visit Bilbao\"],\"articleSection\":[\"Visiter Bilbao\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\\\/\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\\\/\",\"name\":\"4 jours \u00e0 Bilbao : itin\u00e9raire et sites \u00e0 visiter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/sanmames-4-dias-en-bilbao.jpg\",\"datePublished\":\"2025-11-26T15:40:51+00:00\",\"dateModified\":\"2025-11-26T15:44:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/bd9f448a07934bf59af8b87821025bbc\"},\"description\":\"Vous disposez de 4 jours pour visiter Bilbao et ses environs ? Vous avez de la chance ! C\u2019est largement suffisant pour profiter de cette ville anim\u00e9e\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/sanmames-4-dias-en-bilbao.jpg\",\"contentUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/sanmames-4-dias-en-bilbao.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4 jours \u00e0 Bilbao : itin\u00e9raire et sites \u00e0 visiter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#website\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/\",\"name\":\"San Mam\u00e9s\",\"description\":\"Conoce San Mames VIP Area y descubre todos los servicios de los que puedes disfrutar durante un partido o cuando celebres un evento de empresa.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/bd9f448a07934bf59af8b87821025bbc\",\"name\":\"Blog Visit San Mames Athletic Club\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g\",\"caption\":\"Blog Visit San Mames Athletic Club\"},\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/author\\\/blog-vsm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 jours \u00e0 Bilbao : itin\u00e9raire et sites \u00e0 visiter","description":"Vous disposez de 4 jours pour visiter Bilbao et ses environs ? Vous avez de la chance ! C\u2019est largement suffisant pour profiter de cette ville anim\u00e9e","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/","og_locale":"fr_FR","og_type":"article","og_title":"4 jours \u00e0 Bilbao : itin\u00e9raire et sites \u00e0 visiter","og_description":"Vous disposez de 4 jours pour visiter Bilbao et ses environs ? Vous avez de la chance ! C\u2019est largement suffisant pour profiter de cette ville anim\u00e9e","og_url":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/","og_site_name":"San Mam\u00e9s","article_published_time":"2025-11-26T15:40:51+00:00","article_modified_time":"2025-11-26T15:44:54+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2025\/11\/sanmames-4-dias-en-bilbao.jpg","type":"image\/jpeg"}],"author":"Blog Visit San Mames Athletic Club","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Blog Visit San Mames Athletic Club","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/#article","isPartOf":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/"},"author":{"name":"Blog Visit San Mames Athletic Club","@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/bd9f448a07934bf59af8b87821025bbc"},"headline":"4 jours \u00e0 Bilbao : itin\u00e9raire et sites \u00e0 visiter","datePublished":"2025-11-26T15:40:51+00:00","dateModified":"2025-11-26T15:44:54+00:00","mainEntityOfPage":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/"},"wordCount":877,"image":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/#primaryimage"},"thumbnailUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2025\/11\/sanmames-4-dias-en-bilbao.jpg","keywords":["athletic club","mejores sitios bilbao","san mam\u00e9s","Visit Bilbao"],"articleSection":["Visiter Bilbao"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/","url":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/","name":"4 jours \u00e0 Bilbao : itin\u00e9raire et sites \u00e0 visiter","isPartOf":{"@id":"https:\/\/sanmames.athletic-club.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/#primaryimage"},"image":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/#primaryimage"},"thumbnailUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2025\/11\/sanmames-4-dias-en-bilbao.jpg","datePublished":"2025-11-26T15:40:51+00:00","dateModified":"2025-11-26T15:44:54+00:00","author":{"@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/bd9f448a07934bf59af8b87821025bbc"},"description":"Vous disposez de 4 jours pour visiter Bilbao et ses environs ? Vous avez de la chance ! C\u2019est largement suffisant pour profiter de cette ville anim\u00e9e","breadcrumb":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/#primaryimage","url":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2025\/11\/sanmames-4-dias-en-bilbao.jpg","contentUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2025\/11\/sanmames-4-dias-en-bilbao.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/4-jours-a-bilbao-itineraire-et-sites-a-visiter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sanmames.athletic-club.eus\/fr\/"},{"@type":"ListItem","position":2,"name":"4 jours \u00e0 Bilbao : itin\u00e9raire et sites \u00e0 visiter"}]},{"@type":"WebSite","@id":"https:\/\/sanmames.athletic-club.eus\/#website","url":"https:\/\/sanmames.athletic-club.eus\/","name":"San Mam\u00e9s","description":"Conoce San Mames VIP Area y descubre todos los servicios de los que puedes disfrutar durante un partido o cuando celebres un evento de empresa.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sanmames.athletic-club.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/bd9f448a07934bf59af8b87821025bbc","name":"Blog Visit San Mames Athletic Club","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g","caption":"Blog Visit San Mames Athletic Club"},"url":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/author\/blog-vsm\/"}]}},"_links":{"self":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/19702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/users\/296"}],"replies":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/comments?post=19702"}],"version-history":[{"count":3,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/19702\/revisions"}],"predecessor-version":[{"id":19706,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/19702\/revisions\/19706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/media\/19345"}],"wp:attachment":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/media?parent=19702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/categories?post=19702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/tags?post=19702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}