{"id":15516,"date":"2024-11-01T09:00:00","date_gmt":"2024-11-01T08:00:00","guid":{"rendered":"https:\/\/sanmames.athletic-club.eus\/?p=15516"},"modified":"2024-10-28T11:16:08","modified_gmt":"2024-10-28T10:16:08","slug":"evenements-a-bilbao-1-3-novembre","status":"publish","type":"post","link":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-1-3-novembre\/","title":{"rendered":"\u00c9v\u00e9nements \u00e0 Bilbao (1-3 novembre)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><p class='entradilla'>LaLiga revient \u00e0 San Mam\u00e9s avec le match entre l\u2019Athletic Club et le Real Betis. Si vous vous rendez \u00e0 Bilbao pour assister \u00e0 ce match, n\u2019oubliez pas les autres activit\u00e9s int\u00e9ressantes qui se d\u00e9rouleront dans la capitale biscayenne au cours du week-end.<\/p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9v\u00e9nements \u00e0 Bilbao 1-3 novembre 2024<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ce dimanche 3 novembre, <strong>l\u2019Athletic Club affronte le Real Betis<\/strong> \u00e0 domicile. Le coup d\u2019envoi sera donn\u00e9 \u00e0 21h00, et vous pouvez obtenir vos <strong><a href=\"https:\/\/www.athletic-club.eus\/en\/tickets\">billets<\/a><\/strong> pour ce match d\u00e8s maintenant.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u2019oubliez pas que dans <strong>tous les restaurants de San Mam\u00e9s<\/strong> &#8211; <strong><a href=\"https:\/\/sanmamesjatetxea.com\/\">San Mames Jatetxea<\/a>, <a href=\"https:\/\/es.lacampadelosingleses.com\/\">La Campa de los Ingleses<\/a><\/strong> et <strong><a href=\"https:\/\/geuriasanmames.com\/\">Geuria !<\/a><\/strong> &#8211; vous pourrez d\u00e9guster le menu qui vous convient le mieux pendant votre s\u00e9jour \u00e0 Bilbao.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous souhaitez vivre le match comme si vous \u00e9tiez l\u2019un des joueurs, vous pouvez le faire gr\u00e2ce \u00e0 l\u2019exp\u00e9rience <strong>Players Zone Vip<\/strong>. Approchez-vous au plus pr\u00e8s du terrain, asseyez-vous \u00e0 c\u00f4t\u00e9 des joueurs, vivez de pr\u00e8s le processus de prise de d\u00e9cision et profitez de l\u2019&#8217;espace VIP San Mames et de sa gastronomie avant et apr\u00e8s le match.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L&#8217;exp\u00e9rience de la<\/strong> <strong><a href=\"https:\/\/contenidos.athletic-club.eus\/players-zone-vip?utm_source=athletic-club.eus&amp;utm_medium=referral&amp;utm_campaign=players-zone-vip&amp;utm_content=noticia-informacion\">Players Zone VIP<\/a> comprend<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class='swing'><strong>Acc\u00e8s \u00e0 la San Mames VIP Area une heure et demie avant le match et une heure apr\u00e8s <\/strong>la fin du match avec une proposition gastronomique de premier ordre avec la collaboration de chefs \u00e9toil\u00e9s de Biscaye.<\/li>\n\n\n\n<li class='swing'><strong>Assistez \u00e0 l\u2019\u00e9chauffement <\/strong>sur le terrain.<\/li>\n\n\n\n<li class='swing'><strong>Places assises de premier choix avec \u00e9crans <\/strong><strong>\u00e0 c\u00f4t\u00e9 des bancs.<\/strong><\/li>\n\n\n\n<li class='swing'><strong>Pique-nique premium \u00e0 la mi-temps, <\/strong><strong>servi sur place.<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Le tout \u00e0 partir de 425 euros, TVA comprise.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Musique<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ce week-end, le <strong>Stage Live<\/strong> accueillera Victor Rutty et Malezza le vendredi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le vendredi, le <strong>Kafe Antzokia<\/strong> accueillera un concert de Kabaka Pyramid et Salda Dago, tandis que le samedi, Skabidean jouera sur sa sc\u00e8ne pour pr\u00e9senter son nouvel album, et le dimanche, The Courettes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans la <strong>salle Azkena<\/strong>, le vendredi, Ferr\u00e1n Exceso se produira en direct, dans le cadre de sa tourn\u00e9e avec un groupe, et le samedi, le groupe Delt\u00f3, qui rend hommage \u00e0 Extremoduro, se produira !<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Th\u00e9\u00e2tre<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Au <strong>th\u00e9\u00e2tre Arriaga<\/strong>, la pi\u00e8ce \u00ab La Madre \u00bb sera jou\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De m\u00eame, au <strong>th\u00e9\u00e2tre Campos El\u00edseos<\/strong>, l\u2019humour sera \u00e0 l\u2019honneur ces jours-ci, avec le spectacle Chico Glamour le vendredi.<\/p>\n\n\n\n<!--HubSpot Call-to-Action Code --><span class=\"hs-cta-wrapper\" id=\"hs-cta-wrapper-6ecefc74-4ee9-4ff4-9275-63489160f76a\"><span class=\"hs-cta-node hs-cta-6ecefc74-4ee9-4ff4-9275-63489160f76a\" id=\"hs-cta-6ecefc74-4ee9-4ff4-9275-63489160f76a\"><!--[if lte IE 8]><div id=\"hs-cta-ie-element\"><\/div><![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/4626477\/6ecefc74-4ee9-4ff4-9275-63489160f76a\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"hs-cta-img\" id=\"hs-cta-img-6ecefc74-4ee9-4ff4-9275-63489160f76a\" style=\"border-width:0px;\" height=\"465\" width=\"1368\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4626477\/6ecefc74-4ee9-4ff4-9275-63489160f76a.png\"\u2006 \u2006 alt=\"Nueva llamada a la acci\u00f3n\"\/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(4626477, '6ecefc74-4ee9-4ff4-9275-63489160f76a', {\"useNewLoader\":\"true\",\"region\":\"na1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code -->\n","protected":false},"excerpt":{"rendered":"<p>\u00c9v\u00e9nements \u00e0 Bilbao 1-3 novembre 2024 Ce dimanche 3 novembre, l\u2019Athletic Club affronte le Real Betis \u00e0 domicile. Le coup d\u2019envoi sera donn\u00e9 \u00e0 21h00, et vous pouvez obtenir vos billets pour ce match d\u00e8s maintenant.\u00a0 N\u2019oubliez pas que dans tous les restaurants de San Mam\u00e9s &#8211; San Mames Jatetxea, La Campa de los Ingleses [&hellip;]<\/p>\n","protected":false},"author":296,"featured_media":15467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[73],"tags":[241,226,366],"class_list":["post-15516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-visiter-bilbao","tag-eventos-fr","tag-san-mames-fr","tag-visit-bilbao-fr-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9v\u00e9nements \u00e0 Bilbao (1-3 novembre)<\/title>\n<meta name=\"description\" content=\"Si vous vous rendez \u00e0 Bilbao pour assister \u00e0 ce match, n\u2019oubliez pas les autres activit\u00e9s int\u00e9ressantes qui se d\u00e9rouleront dans la capitale biscayenne.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9v\u00e9nements \u00e0 Bilbao (1-3 novembre)\" \/>\n<meta property=\"og:description\" content=\"Si vous vous rendez \u00e0 Bilbao pour assister \u00e0 ce match, n\u2019oubliez pas les autres activit\u00e9s int\u00e9ressantes qui se d\u00e9rouleront dans la capitale biscayenne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/\" \/>\n<meta property=\"og:site_name\" content=\"San Mam\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-01T08:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2024\/11\/athletic-betis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Visit San Mames Athletic Club\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Visit San Mames Athletic Club\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/blog\\\/eventos-en-bilbao-1-3-de-noviembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/blog\\\/eventos-en-bilbao-1-3-de-noviembre\\\/\"},\"author\":{\"name\":\"Blog Visit San Mames Athletic Club\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/bd9f448a07934bf59af8b87821025bbc\"},\"headline\":\"\u00c9v\u00e9nements \u00e0 Bilbao (1-3 novembre)\",\"datePublished\":\"2024-11-01T08:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/blog\\\/eventos-en-bilbao-1-3-de-noviembre\\\/\"},\"wordCount\":394,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/blog\\\/eventos-en-bilbao-1-3-de-noviembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/athletic-betis.jpg\",\"keywords\":[\"eventos\",\"san mam\u00e9s\",\"Visit Bilbao\"],\"articleSection\":[\"Visiter Bilbao\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sanmames.athletic-club.eus\\\/blog\\\/eventos-en-bilbao-1-3-de-noviembre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/blog\\\/eventos-en-bilbao-1-3-de-noviembre\\\/\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/blog\\\/eventos-en-bilbao-1-3-de-noviembre\\\/\",\"name\":\"\u00c9v\u00e9nements \u00e0 Bilbao (1-3 novembre)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/blog\\\/eventos-en-bilbao-1-3-de-noviembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/blog\\\/eventos-en-bilbao-1-3-de-noviembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/athletic-betis.jpg\",\"datePublished\":\"2024-11-01T08:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/bd9f448a07934bf59af8b87821025bbc\"},\"description\":\"Si vous vous rendez \u00e0 Bilbao pour assister \u00e0 ce match, n\u2019oubliez pas les autres activit\u00e9s int\u00e9ressantes qui se d\u00e9rouleront dans la capitale biscayenne.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/blog\\\/eventos-en-bilbao-1-3-de-noviembre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sanmames.athletic-club.eus\\\/blog\\\/eventos-en-bilbao-1-3-de-noviembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/blog\\\/eventos-en-bilbao-1-3-de-noviembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/athletic-betis.jpg\",\"contentUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/athletic-betis.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/blog\\\/eventos-en-bilbao-1-3-de-noviembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e9nements \u00e0 Bilbao (1-3 novembre)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#website\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/\",\"name\":\"San Mam\u00e9s\",\"description\":\"Conoce San Mames VIP Area y descubre todos los servicios de los que puedes disfrutar durante un partido o cuando celebres un evento de empresa.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/bd9f448a07934bf59af8b87821025bbc\",\"name\":\"Blog Visit San Mames Athletic Club\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g\",\"caption\":\"Blog Visit San Mames Athletic Club\"},\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/author\\\/blog-vsm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9v\u00e9nements \u00e0 Bilbao (1-3 novembre)","description":"Si vous vous rendez \u00e0 Bilbao pour assister \u00e0 ce match, n\u2019oubliez pas les autres activit\u00e9s int\u00e9ressantes qui se d\u00e9rouleront dans la capitale biscayenne.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9v\u00e9nements \u00e0 Bilbao (1-3 novembre)","og_description":"Si vous vous rendez \u00e0 Bilbao pour assister \u00e0 ce match, n\u2019oubliez pas les autres activit\u00e9s int\u00e9ressantes qui se d\u00e9rouleront dans la capitale biscayenne.","og_url":"https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/","og_site_name":"San Mam\u00e9s","article_published_time":"2024-11-01T08:00:00+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2024\/11\/athletic-betis.jpg","type":"image\/jpeg"}],"author":"Blog Visit San Mames Athletic Club","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Blog Visit San Mames Athletic Club","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/#article","isPartOf":{"@id":"https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/"},"author":{"name":"Blog Visit San Mames Athletic Club","@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/bd9f448a07934bf59af8b87821025bbc"},"headline":"\u00c9v\u00e9nements \u00e0 Bilbao (1-3 novembre)","datePublished":"2024-11-01T08:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/"},"wordCount":394,"commentCount":0,"image":{"@id":"https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/#primaryimage"},"thumbnailUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2024\/11\/athletic-betis.jpg","keywords":["eventos","san mam\u00e9s","Visit Bilbao"],"articleSection":["Visiter Bilbao"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/","url":"https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/","name":"\u00c9v\u00e9nements \u00e0 Bilbao (1-3 novembre)","isPartOf":{"@id":"https:\/\/sanmames.athletic-club.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/#primaryimage"},"image":{"@id":"https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/#primaryimage"},"thumbnailUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2024\/11\/athletic-betis.jpg","datePublished":"2024-11-01T08:00:00+00:00","author":{"@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/bd9f448a07934bf59af8b87821025bbc"},"description":"Si vous vous rendez \u00e0 Bilbao pour assister \u00e0 ce match, n\u2019oubliez pas les autres activit\u00e9s int\u00e9ressantes qui se d\u00e9rouleront dans la capitale biscayenne.","breadcrumb":{"@id":"https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/#primaryimage","url":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2024\/11\/athletic-betis.jpg","contentUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2024\/11\/athletic-betis.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/sanmames.athletic-club.eus\/blog\/eventos-en-bilbao-1-3-de-noviembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sanmames.athletic-club.eus\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e9nements \u00e0 Bilbao (1-3 novembre)"}]},{"@type":"WebSite","@id":"https:\/\/sanmames.athletic-club.eus\/#website","url":"https:\/\/sanmames.athletic-club.eus\/","name":"San Mam\u00e9s","description":"Conoce San Mames VIP Area y descubre todos los servicios de los que puedes disfrutar durante un partido o cuando celebres un evento de empresa.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sanmames.athletic-club.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/bd9f448a07934bf59af8b87821025bbc","name":"Blog Visit San Mames Athletic Club","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g","caption":"Blog Visit San Mames Athletic Club"},"url":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/author\/blog-vsm\/"}]}},"_links":{"self":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/15516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/users\/296"}],"replies":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/comments?post=15516"}],"version-history":[{"count":1,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/15516\/revisions"}],"predecessor-version":[{"id":15517,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/15516\/revisions\/15517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/media\/15467"}],"wp:attachment":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/media?parent=15516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/categories?post=15516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/tags?post=15516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}