{"id":12948,"date":"2023-11-06T21:55:42","date_gmt":"2023-11-06T20:55:42","guid":{"rendered":"https:\/\/sanmames.athletic-club.eus\/?p=12948"},"modified":"2023-11-06T22:03:12","modified_gmt":"2023-11-06T21:03:12","slug":"evenements-a-bilbao-ce-week-end-10-12-novembre","status":"publish","type":"post","link":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/","title":{"rendered":"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (10-12 novembre)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><p class='entradilla'> Ce vendredi 10 novembre, le championnat revient \u00e0 San Mam\u00e9s. Avec un choc entre les Leones et le Celta Vigo (21h00). Voici quelques-uns des \u00e9v\u00e9nements qui se d\u00e9rouleront \u00e0 Bilbao ce week-end (10-12 novembre). <\/p> <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9v\u00e9nements \u00e0 Bilbao du 10 au 12 novembre 2023<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9v\u00e9nement sportif de ce week-end \u00e0 Bilbao est le match entre <strong>l\u2019Athletic Club<\/strong> <strong>et le Celta de Vigo<\/strong> ce vendredi 10 novembre \u00e0 21h00 au <strong>stade San Mam\u00e9s<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un match au cours duquel La Catedral poussera une fois de plus l\u2019\u00e9quipe rouge et blanche \u00e0 prendre trois points \u00e0 domicile. Un match que vous pourrez vivre et appr\u00e9cier comme un lion gr\u00e2ce \u00e0 <strong><a href=\"https:\/\/contenidos.athletic-club.eus\/the-lion-experience?utm_source=sanmames.athletic-club.eus\/BLOG&amp;utm_medium=referral&amp;utm_campaign=ecosistema-ac&amp;utm_content=experiencias-%C3%BAnicas-para-disfrutar-de-los-partidos-del-athletic-club&amp;_gl=1*q96ppa*_gcl_au*NzM5MDk1NjIyLjE2OTkzMDM4MzY.\">The Lion Experience.<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il s\u2019agit d&#8217;une exp\u00e9rience qui permet d\u2019acc\u00e9der \u00e0 des <strong>espaces r\u00e9serv\u00e9s<\/strong> <strong>exclusivement aux joueurs<\/strong> lors de l&#8217;avant-match, de vivre le match dans les <strong>meilleures places du stade<\/strong> et l&#8217;apr\u00e8s-match de mani\u00e8re unique dans la <strong>zone mixte et la salle de presse, ainsi que de rencontrer un joueur <\/strong>de l\u2019\u00e9quipe premi\u00e8re<strong> en personne<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Que comprend l\u2019exp\u00e9rience Lion ?<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class='swing'><strong>Emplacement centr\u00e9 sur l\u2019anneau VIP avec service gastronomique inclus.<\/strong><\/li>\n\n\n\n<li class='swing'><strong>Pack de bienvenue.<\/strong><\/li>\n\n\n\n<li class='swing'><strong>Visite du vestiaire et du tunnel de l\u2019\u00e9quipe <\/strong><strong>avant l&#8217;arriv\u00e9e des joueurs.<\/strong><\/li>\n\n\n\n<li class='swing'><strong>Exp\u00e9rience exclusive de l\u2019arriv\u00e9e des deux \u00e9quipes au stade.<\/strong><\/li>\n\n\n\n<li class='swing'><strong>Suivre sur le terrain l\u2019<\/strong><strong>\u00e9chauffement<\/strong><strong> d\u2019&#8217;avant-match.<\/strong><\/li>\n\n\n\n<li class='swing'><strong>Acc\u00e8s \u00e0 la <\/strong><strong>salle de presse<\/strong><strong> pour suivre en direct la conf\u00e9rence de presse d&#8217;apr\u00e8s-match.<\/strong><\/li>\n\n\n\n<li class='swing'><strong>Rencontre avec un joueur de l\u2019\u00e9quipe premi\u00e8re dans la zone mixte<\/strong><strong>.<\/strong><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">\u200b<strong>Mus\u00e9es<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous allez voir ce match, vous pouvez profiter de votre passage \u00e0 Bilbao pour visiter certains de ses mus\u00e9es, du <strong>Mus\u00e9e<\/strong><strong> Guggenheim<\/strong> au <strong>Mu<\/strong><strong>s\u00e9<\/strong><strong>e des Beaux-Arts, en passant par le Mu<\/strong><strong>s\u00e9<\/strong><strong>e des reproductions artistiques ou le Mu<\/strong><strong>s\u00e9e<\/strong><strong> maritime.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sans oublier l\u2019<a href=\"https:\/\/sanmames.athletic-club.eus\/museo\/fr\/tour\/\">AC Museoa<\/a>, le <strong>Mus\u00e9e de l\u2019Athletique Club<\/strong>, qui abrite plus de 1 000 objets originaux et vid\u00e9os, qui vous plongeront dans l&#8217;essence de l\u2019\u00e9quipe rouge et blanche. Vous pouvez \u00e9galement faire la <a href=\"https:\/\/sanmames.athletic-club.eus\/museo\/fr\/tour\/\">visite de San Mam\u00e9s<\/a> pour d\u00e9couvrir l&#8217;int\u00e9rieur de la Cath\u00e9drale du football.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une fa\u00e7on unique et diff\u00e9rente de d\u00e9couvrir l\u2019<strong>Athletic Club<\/strong> et son histoire, et l&#8217;un des meilleurs <strong>plans familiaux si vous \u00eates \u00e0 Bilbao<\/strong>. <a href=\"https:\/\/tickets.athletic-club.eus\/athleticclub-museo\/en_US\/tickets?utm_source=google&amp;utm_source=adwords&amp;utm_medium=paid-search&amp;utm_medium=ppc&amp;utm_campaign=ACmuseoa&amp;utm_campaign=B%C3%BAsqueda%20%7C%20Museo%20%2B%20Tour&amp;utm_term=museo%20athletic%20entradas&amp;hsa_acc=1470599878&amp;hsa_cam=15387496283&amp;hsa_grp=136989162464&amp;hsa_ad=564612091383&amp;hsa_src=g&amp;hsa_tgt=kwd-1492751842056&amp;hsa_kw=museo%20athletic%20entradas&amp;hsa_mt=p&amp;hsa_net=adwords&amp;hsa_ver=3&amp;gclid=Cj0KCQjwxYOiBhC9ARIsANiEIfanqHIwfkfBThEtlPzj7tV3r2qHR-HB4ZeegY3esvR1drkRNml0JNwaAqoeEALw_wcB&amp;_gl=1*1ceatfc*_gcl_au*NzM5MDk1NjIyLjE2OTkzMDM4MzY.*_ga*MTc4OTcxMzk1NC4xNjk5MzAzODM2*_ga_48976NX8KF*MTY5OTMwMzgzNi4xLjEuMTY5OTMwMzk3Ni40OC4wLjA.\">R\u00e9servez d\u00e8s maintenant votre visite au mus\u00e9e<\/a> de l\u2019Athletic Club.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u200b<strong>Concerts<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La capitale de la Biscaye accueillera plusieurs concerts au cours des prochains jours. Daniel Higi\u00e9nico se produira en direct au <strong>Cotton Club<\/strong> le samedi 11 \u00e0 20h00. Le dimanche 12, Yomil Champions se produira au <strong>Santana 27<\/strong> (21h00). Et au <strong>Kafe Antzokia<\/strong>, le samedi 11, les groupes Iskanbila et Kaleko Urdangak monteront sur sc\u00e8ne (22h00).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u200b<strong>Th\u00e9\u00e2tre<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En ce qui concerne les arts du spectacle, le <strong>Th\u00e9\u00e2tre Arriaga<\/strong> accueillera samedi et dimanche la repr\u00e9sentation de Malos tiempos para la l\u00edrica <em>(Mauvais temps pour le lyrique).<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par ailleurs, le <strong>Th\u00e9\u00e2tre Campos<\/strong> organisera diff\u00e9rents \u00e9v\u00e9nements ce week-end, comme le concert de Mikel Bizar le samedi 11 et, un jour plus tard, le monologue d\u2019&#8217;Andreu Casanova.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De plus, si vous souhaitez vous ressourcer pendant votre <strong>visite \u00e0 Bilbao<\/strong>, vous pouvez le faire dans l\u2019un de nos restaurants: <strong><a href=\"https:\/\/sanmamesjatetxea.com\/?lang=en\">San Mames Jatetxea<\/a><\/strong>, <strong><a href=\"https:\/\/es.lacampadelosingleses.com\/?utm_source=sanmames.athletic-club.eus\/BLOG&amp;utm_medium=referral&amp;utm_campaign=ecosistema-ac&amp;utm_content=eventos-en-bilbao-este-fin-de-semana-(10-12-de-noviembre)\">La Campa de los Ingleses<\/a><\/strong> et <strong><a href=\"https:\/\/geuriasanmames.com\/?utm_source=sanmames.athletic-club.eus\/BLOG&amp;utm_medium=referral&amp;utm_campaign=ecosistema-ac&amp;utm_content=eventos-en-bilbao-este-fin-de-semana-(28-de-abril-%E2%80%93-1-de-mayo)\">Geuria<\/a><\/strong>, o\u00f9 vous trouverez des menus pour tous les go\u00fbts dans un cadre unique.<\/p>\n\n\n\n<!--HubSpot Call-to-Action Code --><span class=\"hs-cta-wrapper\" id=\"hs-cta-wrapper-6ecefc74-4ee9-4ff4-9275-63489160f76a\"><span class=\"hs-cta-node hs-cta-6ecefc74-4ee9-4ff4-9275-63489160f76a\" id=\"hs-cta-6ecefc74-4ee9-4ff4-9275-63489160f76a\"><!--[if lte IE 8]><div id=\"hs-cta-ie-element\"><\/div><![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/4626477\/6ecefc74-4ee9-4ff4-9275-63489160f76a\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"hs-cta-img\" id=\"hs-cta-img-6ecefc74-4ee9-4ff4-9275-63489160f76a\" style=\"border-width:0px;\" height=\"465\" width=\"1368\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4626477\/6ecefc74-4ee9-4ff4-9275-63489160f76a.png\"\u2006 \u2006 alt=\"Nueva llamada a la acci\u00f3n\"\/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(4626477, '6ecefc74-4ee9-4ff4-9275-63489160f76a', {\"useNewLoader\":\"true\",\"region\":\"na1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code -->\n","protected":false},"excerpt":{"rendered":"<p>\u00c9v\u00e9nements \u00e0 Bilbao du 10 au 12 novembre 2023 L\u2019\u00e9v\u00e9nement sportif de ce week-end \u00e0 Bilbao est le match entre l\u2019Athletic Club et le Celta de Vigo ce vendredi 10 novembre \u00e0 21h00 au stade San Mam\u00e9s. Un match au cours duquel La Catedral poussera une fois de plus l\u2019\u00e9quipe rouge et blanche \u00e0 prendre [&hellip;]<\/p>\n","protected":false},"author":296,"featured_media":12829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[73],"tags":[241,226,366],"class_list":["post-12948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-visiter-bilbao","tag-eventos-fr","tag-san-mames-fr","tag-visit-bilbao-fr-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (10-12 novembre)<\/title>\n<meta name=\"description\" content=\"Voici quelques-uns des \u00e9v\u00e9nements qui se d\u00e9rouleront \u00e0 Bilbao ce week-end (10-12 novembre).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (10-12 novembre)\" \/>\n<meta property=\"og:description\" content=\"Voici quelques-uns des \u00e9v\u00e9nements qui se d\u00e9rouleront \u00e0 Bilbao ce week-end (10-12 novembre).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/\" \/>\n<meta property=\"og:site_name\" content=\"San Mam\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-06T20:55:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-06T21:03:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/11\/eventos-bilbao-10-12-noviembre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Visit San Mames Athletic Club\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Visit San Mames Athletic Club\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-10-12-novembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-10-12-novembre\\\/\"},\"author\":{\"name\":\"Blog Visit San Mames Athletic Club\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/bd9f448a07934bf59af8b87821025bbc\"},\"headline\":\"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (10-12 novembre)\",\"datePublished\":\"2023-11-06T20:55:42+00:00\",\"dateModified\":\"2023-11-06T21:03:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-10-12-novembre\\\/\"},\"wordCount\":571,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-10-12-novembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/eventos-bilbao-10-12-noviembre.jpg\",\"keywords\":[\"eventos\",\"san mam\u00e9s\",\"Visit Bilbao\"],\"articleSection\":[\"Visiter Bilbao\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-10-12-novembre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-10-12-novembre\\\/\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-10-12-novembre\\\/\",\"name\":\"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (10-12 novembre)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-10-12-novembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-10-12-novembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/eventos-bilbao-10-12-noviembre.jpg\",\"datePublished\":\"2023-11-06T20:55:42+00:00\",\"dateModified\":\"2023-11-06T21:03:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/bd9f448a07934bf59af8b87821025bbc\"},\"description\":\"Voici quelques-uns des \u00e9v\u00e9nements qui se d\u00e9rouleront \u00e0 Bilbao ce week-end (10-12 novembre).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-10-12-novembre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-10-12-novembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-10-12-novembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/eventos-bilbao-10-12-noviembre.jpg\",\"contentUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/eventos-bilbao-10-12-noviembre.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-10-12-novembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (10-12 novembre)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#website\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/\",\"name\":\"San Mam\u00e9s\",\"description\":\"Conoce San Mames VIP Area y descubre todos los servicios de los que puedes disfrutar durante un partido o cuando celebres un evento de empresa.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/bd9f448a07934bf59af8b87821025bbc\",\"name\":\"Blog Visit San Mames Athletic Club\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g\",\"caption\":\"Blog Visit San Mames Athletic Club\"},\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/author\\\/blog-vsm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (10-12 novembre)","description":"Voici quelques-uns des \u00e9v\u00e9nements qui se d\u00e9rouleront \u00e0 Bilbao ce week-end (10-12 novembre).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (10-12 novembre)","og_description":"Voici quelques-uns des \u00e9v\u00e9nements qui se d\u00e9rouleront \u00e0 Bilbao ce week-end (10-12 novembre).","og_url":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/","og_site_name":"San Mam\u00e9s","article_published_time":"2023-11-06T20:55:42+00:00","article_modified_time":"2023-11-06T21:03:12+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/11\/eventos-bilbao-10-12-noviembre.jpg","type":"image\/jpeg"}],"author":"Blog Visit San Mames Athletic Club","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Blog Visit San Mames Athletic Club","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/#article","isPartOf":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/"},"author":{"name":"Blog Visit San Mames Athletic Club","@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/bd9f448a07934bf59af8b87821025bbc"},"headline":"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (10-12 novembre)","datePublished":"2023-11-06T20:55:42+00:00","dateModified":"2023-11-06T21:03:12+00:00","mainEntityOfPage":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/"},"wordCount":571,"commentCount":0,"image":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/#primaryimage"},"thumbnailUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/11\/eventos-bilbao-10-12-noviembre.jpg","keywords":["eventos","san mam\u00e9s","Visit Bilbao"],"articleSection":["Visiter Bilbao"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/","url":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/","name":"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (10-12 novembre)","isPartOf":{"@id":"https:\/\/sanmames.athletic-club.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/#primaryimage"},"image":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/#primaryimage"},"thumbnailUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/11\/eventos-bilbao-10-12-noviembre.jpg","datePublished":"2023-11-06T20:55:42+00:00","dateModified":"2023-11-06T21:03:12+00:00","author":{"@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/bd9f448a07934bf59af8b87821025bbc"},"description":"Voici quelques-uns des \u00e9v\u00e9nements qui se d\u00e9rouleront \u00e0 Bilbao ce week-end (10-12 novembre).","breadcrumb":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/#primaryimage","url":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/11\/eventos-bilbao-10-12-noviembre.jpg","contentUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/11\/eventos-bilbao-10-12-noviembre.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-10-12-novembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sanmames.athletic-club.eus\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (10-12 novembre)"}]},{"@type":"WebSite","@id":"https:\/\/sanmames.athletic-club.eus\/#website","url":"https:\/\/sanmames.athletic-club.eus\/","name":"San Mam\u00e9s","description":"Conoce San Mames VIP Area y descubre todos los servicios de los que puedes disfrutar durante un partido o cuando celebres un evento de empresa.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sanmames.athletic-club.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/bd9f448a07934bf59af8b87821025bbc","name":"Blog Visit San Mames Athletic Club","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g","caption":"Blog Visit San Mames Athletic Club"},"url":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/author\/blog-vsm\/"}]}},"_links":{"self":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/12948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/users\/296"}],"replies":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/comments?post=12948"}],"version-history":[{"count":1,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/12948\/revisions"}],"predecessor-version":[{"id":12949,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/12948\/revisions\/12949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/media\/12829"}],"wp:attachment":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/media?parent=12948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/categories?post=12948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/tags?post=12948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}