{"id":12220,"date":"2023-09-13T09:47:18","date_gmt":"2023-09-13T07:47:18","guid":{"rendered":"https:\/\/sanmames.athletic-club.eus\/?p=12220"},"modified":"2023-09-13T09:48:16","modified_gmt":"2023-09-13T07:48:16","slug":"evenements-a-bilbao-ce-week-end-15-17-septembre","status":"publish","type":"post","link":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/","title":{"rendered":"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (15-17 septembre)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><p class='entradilla'> Ce samedi 16 septembre, LaLiga revient \u00e0 San Mam\u00e9s avec le match entre l&#8217;Athletic Club et le C\u00e1diz FC (14h00). Voici quelques-uns des \u00e9v\u00e9nements qui auront lieu \u00e0 Bilbao ce week-end (15-17 septembre). <\/p> <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00c9v\u00e9nements \u00e0 Bilbao du 15 au 17 septembre 2023<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bilbao pr\u00e9sente un important programme d\u2019\u00e9v\u00e9nements pour l&#8217;avant-dernier week-end de l\u2019\u00e9t\u00e9 2023. L&#8217;un des temps forts est le match entre <strong><a href=\"https:\/\/tickets.athletic-club.eus\/athleticclub_web\/en_US\/entradas\/evento\/31122\/session\/1750182\/select?%3Futm_source=google-ads&amp;utm_medium=cpc&amp;utm_medium=ppc&amp;utm_campaign=ticketing-partidos&amp;utm_campaign=AC%20%C2%B7%20SEV%20%C2%B7%20dic%2021&amp;utm_content=origen-cadiz-cf&amp;utm_term=entradas%20san%20mames&amp;utm_source=adwords&amp;hsa_acc=1470599878&amp;hsa_cam=17107726227&amp;hsa_grp=148183906200&amp;hsa_ad=671769729000&amp;hsa_src=g&amp;hsa_tgt=kwd-313667359825&amp;hsa_kw=entradas%20san%20mames&amp;hsa_mt=e&amp;hsa_net=adwords&amp;hsa_ver=3&amp;viewCode=V_blockmap_view&amp;_gl=1*m1p31v*_gcl_aw*R0NMLjE2OTQ1OTA0MDUuQ2owS0NRand4WU9pQmhDOUFSSXNBTmlFSWZhbnFISXdma2ZCVGhFdGxQemo3dFYzcjJxSFItSEI0WmVlZ1kzZXN2UjFkcmtSTm1sMEpOd2FBcW9lRUFMd193Y0I.*_gcl_au*MTYwNDg1NDA1OS4xNjk0NTkwMDY2*_ga*MTQ5MzIzMzU5OC4xNjk0NTkwMDY3*_ga_48976NX8KF*MTY5NDU5MDA2Ni4xLjEuMTY5NDU5MDc2MC42MC4wLjA.\">l&#8217;Athletic Club et le C\u00e1diz FC<\/a><\/strong> ce samedi 16 septembre \u00e0 14h00 au <strong>stade San Mam\u00e9s<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/07\/san-mames-vip-area-1024x576.jpg\" alt=\"\" class=\"wp-image-11935\" srcset=\"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/07\/san-mames-vip-area-1024x576.jpg 1024w, https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/07\/san-mames-vip-area-300x169.jpg 300w, https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/07\/san-mames-vip-area-768x432.jpg 768w, https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/07\/san-mames-vip-area.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Un match important au cours duquel les lions tenteront d&#8217;obtenir leur deuxi\u00e8me victoire \u00e0 domicile apr\u00e8s l&#8217;inoubliable victoire contre une autre \u00e9quipe andalouse, le Betis. N&#8217;oubliez pas que vous pouvez profiter de ce match d&#8217;une mani\u00e8re unique en b\u00e9n\u00e9ficiant de tous ces services gr\u00e2ce \u00e0 votre <a href=\"https:\/\/tickets.athletic-club.eus\/vipathleticclub_web\/en_US\/entradas\/evento\/31122\">Matchday VIP Experience<\/a> :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class='swing'><strong>Emplacement privil\u00e9gi\u00e9 \u00e0 l&#8217;int\u00e9rieur du stade.<\/strong> Choisissez votre place parmi celles disponibles dans les tribunes Nord, Est et Principale de l&#8217;anneau central de San Mam\u00e9s.<\/li>\n\n\n\n<li class='swing'><strong>Service gastronomique exclusif inclus avec notre s\u00e9lection de chefs biscayens avec 11 \u00e9toiles Michelin.<\/strong> Andra Mari, Azurmendi, Eneko, Boroa, Etxanobe, Garena, Nerua Guggenheim Bilbao, Zarate et Zortziko sont les restaurants charg\u00e9s de cuisiner chaque jour de match.<\/li>\n\n\n\n<li class='swing'><strong>Acc\u00e8s d&#8217;une heure et demie avant \u00e0 une heure apr\u00e8s le match.<\/strong> Vous pourrez vivre l&#8217;atmosph\u00e8re d&#8217;avant et d&#8217;apr\u00e8s match d&#8217;une mani\u00e8re diff\u00e9rente.<\/li>\n\n\n\n<li class='swing'><strong>Acc\u00e8s \u00e0 l&#8217;ensemble de l&#8217;anneau central partag\u00e9 par les loges VIP, les abonn\u00e9s VIP et les utilisateurs de Matchday Experience.<\/strong> Vous b\u00e9n\u00e9ficierez d&#8217;un service personnalis\u00e9 et disposerez de tout le confort n\u00e9cessaire.<\/li>\n\n\n\n<li class='swing'><strong>Des \u00e9crans avec la couverture du match en direct, les rediffusions et tous les d\u00e9tails.<\/strong><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Mus\u00e9es<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Pendant ce week-end, vous pourrez visiter l&#8217;un des nombreux mus\u00e9es de Bilbao, tels que le Mus\u00e9e Guggenheim, <strong>le Mus\u00e9e des Beaux-Arts, le Mus\u00e9e des Reproductions Artistiques et le Mus\u00e9e Maritime.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sans oublier <strong>l&#8217;un des meilleurs plans familiaux que l&#8217;on puisse faire \u00e0 Bilbao<\/strong> : la visite du <strong><a href=\"https:\/\/sanmames.athletic-club.eus\/museo\/fr\/\">AC Museoa<\/a><\/strong> , compos\u00e9 de plus de 1 000 objets originaux et de vid\u00e9os qui vous feront d\u00e9couvrir l&#8217;essence de l&#8217;\u00e9quipe rouge et blanche et qui vous permettra \u00e9galement de faire le <a href=\"https:\/\/sanmames.athletic-club.eus\/museo\/fr\/tour\/\">San Mam\u00e9s Tour<\/a> pour conna\u00eetre l&#8217;int\u00e9rieur de la cath\u00e9drale du football. Une fa\u00e7on unique de d\u00e9couvrir ce que repr\u00e9sente l&#8217;Athletic Club et de conna\u00eetre son histoire, et l&#8217;un des meilleurs <strong>plans familiaux si vous \u00eates \u00e0 Bilbao<\/strong>. Rien qu&#8217;entre juillet et ao\u00fbt, pr\u00e8s de 45 000 personnes ont visit\u00e9 l&#8217;AC Museoa et le San Mam\u00e9s Tour. <a href=\"https:\/\/tickets.athletic-club.eus\/athleticclub-museo\/en_US\/tickets?utm_source=google&amp;utm_source=adwords&amp;utm_medium=paid-search&amp;utm_medium=ppc&amp;utm_campaign=ACmuseoa&amp;utm_campaign=B%C3%BAsqueda%20%7C%20Museo%20%2B%20Tour&amp;utm_term=museo%20athletic%20entradas&amp;hsa_acc=1470599878&amp;hsa_cam=15387496283&amp;hsa_grp=136989162464&amp;hsa_ad=564612091383&amp;hsa_src=g&amp;hsa_tgt=kwd-1492751842056&amp;hsa_kw=museo%20athletic%20entradas&amp;hsa_mt=p&amp;hsa_net=adwords&amp;hsa_ver=3&amp;gclid=Cj0KCQjwxYOiBhC9ARIsANiEIfanqHIwfkfBThEtlPzj7tV3r2qHR-HB4ZeegY3esvR1drkRNml0JNwaAqoeEALw_wcB&amp;_gl=1*17calia*_gcl_aw*R0NMLjE2OTQ1OTA5NDYuQ2owS0NRand4WU9pQmhDOUFSSXNBTmlFSWZhZzRJVmlXWUp2NWtGMTd3THJUTk93aUVtakJJbEExWjc2OFRyUVd1MDltVWMtazREbVRSd2FBdWVjRUFMd193Y0I.*_gcl_au*MTYwNDg1NDA1OS4xNjk0NTkwMDY2*_ga*MTQ5MzIzMzU5OC4xNjk0NTkwMDY3*_ga_48976NX8KF*MTY5NDU5MDA2Ni4xLjEuMTY5NDU5MTE2NC41Ni4wLjA.\">R\u00e9servez d\u00e8s maintenant votre visite au mus\u00e9e de l&#8217;Athletic Club<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"514\" src=\"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2022\/05\/athletic-ac-museoa-jugadores-1024x514.jpg\" alt=\"\" class=\"wp-image-5439\" srcset=\"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2022\/05\/athletic-ac-museoa-jugadores-1024x514.jpg 1024w, https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2022\/05\/athletic-ac-museoa-jugadores-300x151.jpg 300w, https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2022\/05\/athletic-ac-museoa-jugadores-768x386.jpg 768w, https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2022\/05\/athletic-ac-museoa-jugadores.jpg 1300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Une fa\u00e7on unique de d\u00e9couvrir San Mam\u00e9s est de se ressourcer dans l&#8217;un de nos restaurants, <strong><a href=\"https:\/\/sanmamesjatetxea.com\/?lang=en\">San Mames Jatetxea<\/a>, <a href=\"https:\/\/es.lacampadelosingleses.com\/?utm_source=sanmames.athletic-club.eus\/BLOG&amp;utm_medium=referral&amp;utm_campaign=ecosistema-ac&amp;utm_content=eventos-en-bilbao-este-fin-de-semana-(28-de-abril-%E2%80%93-1-de-mayo)\">La Campa de los Ingleses<\/a> et <a href=\"https:\/\/geuriasanmames.com\/?utm_source=sanmames.athletic-club.eus\/BLOG&amp;utm_medium=referral&amp;utm_campaign=ecosistema-ac&amp;utm_content=eventos-en-bilbao-este-fin-de-semana-(28-de-abril-%E2%80%93-1-de-mayo)\">Geuria<\/a><\/strong>, qui proposent des menus pour tous les go\u00fbts.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Concerts<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La capitale biscayenne accueillera \u00e9galement de nombreux concerts, comme celui de Cutback le samedi 16 septembre au <strong>Cotton Club<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au <strong>Santana 27<\/strong>, le groupe No te va a gustar se produira le samedi 16, suivi de Nestor Pablo le lendemain. Au <strong>Kafe Antzokia<\/strong>, le samedi 16, Noa and the Hell Drinkers et The Half Nelsons se produiront.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Th\u00e9\u00e2tre<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En ce qui concerne les arts du spectacle, le <strong>Teatro Arriaga<\/strong> accueillera vendredi, samedi et dimanche les repr\u00e9sentations de Pl\u00e1tanos, Cacahuetes y Lo que el viento se llev\u00f3 <em>(Bananes, cacahu\u00e8tes et Autant en emporte le vent)<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En outre, le <strong>Teatro Campos<\/strong> pr\u00e9sentera ce week-end la com\u00e9die musicale Cruz de Navajas, avec les meilleures chansons du groupe Mecano.<\/p>\n\n\n\n<!--HubSpot Call-to-Action Code --><span class=\"hs-cta-wrapper\" id=\"hs-cta-wrapper-6ecefc74-4ee9-4ff4-9275-63489160f76a\"><span class=\"hs-cta-node hs-cta-6ecefc74-4ee9-4ff4-9275-63489160f76a\" id=\"hs-cta-6ecefc74-4ee9-4ff4-9275-63489160f76a\"><!--[if lte IE 8]><div id=\"hs-cta-ie-element\"><\/div><![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/4626477\/6ecefc74-4ee9-4ff4-9275-63489160f76a\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"hs-cta-img\" id=\"hs-cta-img-6ecefc74-4ee9-4ff4-9275-63489160f76a\" style=\"border-width:0px;\" height=\"465\" width=\"1368\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4626477\/6ecefc74-4ee9-4ff4-9275-63489160f76a.png\"\u2006 \u2006 alt=\"Nueva llamada a la acci\u00f3n\"\/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(4626477, '6ecefc74-4ee9-4ff4-9275-63489160f76a', {\"useNewLoader\":\"true\",\"region\":\"na1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code -->\n","protected":false},"excerpt":{"rendered":"<p>\u00c9v\u00e9nements \u00e0 Bilbao du 15 au 17 septembre 2023 Bilbao pr\u00e9sente un important programme d\u2019\u00e9v\u00e9nements pour l&#8217;avant-dernier week-end de l\u2019\u00e9t\u00e9 2023. L&#8217;un des temps forts est le match entre l&#8217;Athletic Club et le C\u00e1diz FC ce samedi 16 septembre \u00e0 14h00 au stade San Mam\u00e9s. Un match important au cours duquel les lions tenteront d&#8217;obtenir [&hellip;]<\/p>\n","protected":false},"author":296,"featured_media":12168,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[73],"tags":[377,254,226,366],"class_list":["post-12220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-visiter-bilbao","tag-lathletic-club-museoa","tag-mejores-sitios-bilbao-fr","tag-san-mames-fr","tag-visit-bilbao-fr-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (15-17 septembre)<\/title>\n<meta name=\"description\" content=\"Voici quelques-uns des \u00e9v\u00e9nements qui auront lieu \u00e0 Bilbao ce week-end (15-17 septembre).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (15-17 septembre)\" \/>\n<meta property=\"og:description\" content=\"Voici quelques-uns des \u00e9v\u00e9nements qui auront lieu \u00e0 Bilbao ce week-end (15-17 septembre).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/\" \/>\n<meta property=\"og:site_name\" content=\"San Mam\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-13T07:47:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-13T07:48:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/09\/eventos-bilbao-15-17-septiembre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Visit San Mames Athletic Club\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Visit San Mames Athletic Club\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-15-17-septembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-15-17-septembre\\\/\"},\"author\":{\"name\":\"Blog Visit San Mames Athletic Club\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/bd9f448a07934bf59af8b87821025bbc\"},\"headline\":\"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (15-17 septembre)\",\"datePublished\":\"2023-09-13T07:47:18+00:00\",\"dateModified\":\"2023-09-13T07:48:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-15-17-septembre\\\/\"},\"wordCount\":631,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-15-17-septembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/eventos-bilbao-15-17-septiembre.jpg\",\"keywords\":[\"l\u2019Athletic Club Museoa\",\"mejores sitios bilbao\",\"san mam\u00e9s\",\"Visit Bilbao\"],\"articleSection\":[\"Visiter Bilbao\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-15-17-septembre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-15-17-septembre\\\/\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-15-17-septembre\\\/\",\"name\":\"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (15-17 septembre)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-15-17-septembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-15-17-septembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/eventos-bilbao-15-17-septiembre.jpg\",\"datePublished\":\"2023-09-13T07:47:18+00:00\",\"dateModified\":\"2023-09-13T07:48:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/bd9f448a07934bf59af8b87821025bbc\"},\"description\":\"Voici quelques-uns des \u00e9v\u00e9nements qui auront lieu \u00e0 Bilbao ce week-end (15-17 septembre).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-15-17-septembre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-15-17-septembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-15-17-septembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/eventos-bilbao-15-17-septiembre.jpg\",\"contentUrl\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/eventos-bilbao-15-17-septiembre.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/evenements-a-bilbao-ce-week-end-15-17-septembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (15-17 septembre)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#website\",\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/\",\"name\":\"San Mam\u00e9s\",\"description\":\"Conoce San Mames VIP Area y descubre todos los servicios de los que puedes disfrutar durante un partido o cuando celebres un evento de empresa.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/#\\\/schema\\\/person\\\/bd9f448a07934bf59af8b87821025bbc\",\"name\":\"Blog Visit San Mames Athletic Club\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g\",\"caption\":\"Blog Visit San Mames Athletic Club\"},\"url\":\"https:\\\/\\\/sanmames.athletic-club.eus\\\/fr\\\/blog\\\/author\\\/blog-vsm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (15-17 septembre)","description":"Voici quelques-uns des \u00e9v\u00e9nements qui auront lieu \u00e0 Bilbao ce week-end (15-17 septembre).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (15-17 septembre)","og_description":"Voici quelques-uns des \u00e9v\u00e9nements qui auront lieu \u00e0 Bilbao ce week-end (15-17 septembre).","og_url":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/","og_site_name":"San Mam\u00e9s","article_published_time":"2023-09-13T07:47:18+00:00","article_modified_time":"2023-09-13T07:48:16+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/09\/eventos-bilbao-15-17-septiembre.jpg","type":"image\/jpeg"}],"author":"Blog Visit San Mames Athletic Club","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Blog Visit San Mames Athletic Club","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/#article","isPartOf":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/"},"author":{"name":"Blog Visit San Mames Athletic Club","@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/bd9f448a07934bf59af8b87821025bbc"},"headline":"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (15-17 septembre)","datePublished":"2023-09-13T07:47:18+00:00","dateModified":"2023-09-13T07:48:16+00:00","mainEntityOfPage":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/"},"wordCount":631,"commentCount":0,"image":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/#primaryimage"},"thumbnailUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/09\/eventos-bilbao-15-17-septiembre.jpg","keywords":["l\u2019Athletic Club Museoa","mejores sitios bilbao","san mam\u00e9s","Visit Bilbao"],"articleSection":["Visiter Bilbao"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/","url":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/","name":"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (15-17 septembre)","isPartOf":{"@id":"https:\/\/sanmames.athletic-club.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/#primaryimage"},"image":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/#primaryimage"},"thumbnailUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/09\/eventos-bilbao-15-17-septiembre.jpg","datePublished":"2023-09-13T07:47:18+00:00","dateModified":"2023-09-13T07:48:16+00:00","author":{"@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/bd9f448a07934bf59af8b87821025bbc"},"description":"Voici quelques-uns des \u00e9v\u00e9nements qui auront lieu \u00e0 Bilbao ce week-end (15-17 septembre).","breadcrumb":{"@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/#primaryimage","url":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/09\/eventos-bilbao-15-17-septiembre.jpg","contentUrl":"https:\/\/sanmames.athletic-club.eus\/wp-content\/uploads\/2023\/09\/eventos-bilbao-15-17-septiembre.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/evenements-a-bilbao-ce-week-end-15-17-septembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sanmames.athletic-club.eus\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e9nements \u00e0 Bilbao ce week-end (15-17 septembre)"}]},{"@type":"WebSite","@id":"https:\/\/sanmames.athletic-club.eus\/#website","url":"https:\/\/sanmames.athletic-club.eus\/","name":"San Mam\u00e9s","description":"Conoce San Mames VIP Area y descubre todos los servicios de los que puedes disfrutar durante un partido o cuando celebres un evento de empresa.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sanmames.athletic-club.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/sanmames.athletic-club.eus\/#\/schema\/person\/bd9f448a07934bf59af8b87821025bbc","name":"Blog Visit San Mames Athletic Club","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bec12361a813f7c313eab23381acd22e1c6a2ec97662561b29033a8a5fa4a964?s=96&d=mm&r=g","caption":"Blog Visit San Mames Athletic Club"},"url":"https:\/\/sanmames.athletic-club.eus\/fr\/blog\/author\/blog-vsm\/"}]}},"_links":{"self":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/12220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/users\/296"}],"replies":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/comments?post=12220"}],"version-history":[{"count":1,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/12220\/revisions"}],"predecessor-version":[{"id":12221,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/posts\/12220\/revisions\/12221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/media\/12168"}],"wp:attachment":[{"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/media?parent=12220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/categories?post=12220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sanmames.athletic-club.eus\/fr\/wp-json\/wp\/v2\/tags?post=12220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}